{"id":10004,"date":"2014-04-02T04:00:57","date_gmt":"2014-04-02T04:00:57","guid":{"rendered":"http:\/\/labestiadeportiva.com\/lbd\/?p=10004"},"modified":"2014-04-02T04:01:58","modified_gmt":"2014-04-02T04:01:58","slug":"haciendo-historia-3","status":"publish","type":"post","link":"http:\/\/labestiadeportiva.com\/lbd\/haciendo-historia-3\/","title":{"rendered":"Haciendo historia"},"content":{"rendered":"<p><em>Por MZL Deportes (Corresponsal LBD en Buenos Aires)<\/em><\/p>\n<figure id=\"attachment_10005\" aria-describedby=\"caption-attachment-10005\" style=\"width: 270px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/04\/MZL.jpg\"><img loading=\"lazy\" class=\"wp-image-10005 \" title=\"Vapo x2\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/04\/MZL.jpg\" alt=\"\" width=\"270\" height=\"480\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/04\/MZL.jpg 450w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/04\/MZL-168x300.jpg 168w\" sizes=\"(max-width: 270px) 100vw, 270px\" \/><\/a><figcaption id=\"caption-attachment-10005\" class=\"wp-caption-text\">Credit Photo: Pasi\u00f3n Futsal<\/figcaption><\/figure>\n<p>Tras la medalla plateada en los Juegos Odesur, los fueguinos Alamiro y \u201cKiki\u201d Vaporaki concretaron un resultado que quedar\u00e1 en el libro dorado del Futsal AFA, adjudic\u00e1ndose la Copa de las Naciones en suelo brasilero tras comenzar 0-2 abajo y vencer 3-2 a falta de 14 segundos.<!--moreLeer nota completa --><\/p>\n<p>Los futbolistas nacidos en la capital provincial, Alamiro y Constantino Vaporaki, ven\u00edan con la chapa de haber sido goleador y segundo m\u00e1ximo artillero del seleccionado nacional en los Odesur y buscaban un hito in\u00e9dito para la disciplina: ganar la copa en Brasil ante el combinado local. No hab\u00eda mejor forma de cumplir el objetivo.<\/p>\n<p>La faena comenz\u00f3 \u00e1spera chocando con los paraguayos que ven\u00edan dolidos del 1-6 de los Juegos y llegaron a Uberlandia con sus m\u00e1ximas figuras. Sin embargo, a pesar de arrancar abajo en el marcador, los dirigidos por Diego Giustozzi sacaron pecho y dieron vuelta el resultado para terminar festejando por 3-1 con un grito del mayor de los hermanos fueguinos.<\/p>\n<p>En segundo t\u00e9rmino lleg\u00f3 la hora de reeditar el duelo con Chile, y decimos reeditar porque el tr\u00e1mite fue similar al de los Odesur. Trabado, con los trasandinos esperando una contra letal y pocos goles, el tanteador termin\u00f3 favoreciendo a la albiceleste por 2-1 con un nuevo gol de Alamiro.<\/p>\n<p>Tras estas dos victorias, el fixture de la Copa de las Naciones avizoraba una revancha ante la \u201cCanarinha\u201d que ven\u00eda de ser campeona en los Odesur. Y el panorama de la final comenz\u00f3 cuesta arriba.<\/p>\n<p>Dos goles brasileros en la primera etapa parec\u00edan sentenciar el cotejo, aunque Argentina demostraba buen juego salvo los problemas para vulnerar a la defensa local en los \u00faltimos metros. El complemento iba a ser diferente, con la albiceleste pasando por encima a su rival y emparejando las acciones a trav\u00e9s de Francini y Basile.<\/p>\n<p>No obstante, faltaba lo mejor. Cuando quedaban tres minutos, Giustozzi se la jug\u00f3 y mand\u00f3 al capit\u00e1n Santiago Basile como arquero-jugador para buscar el triunfo. Despu\u00e9s de tanta rotaci\u00f3n, con los cinco jugadores en campo contrario, lleg\u00f3 el premio mayor mediante un zurdazo de Basile que desat\u00f3 el delirio de todo el banco de suplentes. Silencio brutal en el estadio y reclamos por Falcao fueron la despedida menos ansiada para los verdeamarelhos que sufrieron la primera derrota en su pa\u00eds ante la Argentina.<\/p>\n<p>Para comprender mejor el significado de un resultado tan importante, dialogamos con los representantes provinciales y esto fue lo que nos dec\u00edan:<\/p>\n<p>Alamiro Vaporaki: <em><span style=\"color: #ff0000;\">\u201cEl resultado que conseguimos en Brasil es algo hist\u00f3rico, que nunca podr\u00e9 olvidar. Es emocionante por donde se lo mire pero m\u00e1s all\u00e1 de eso lo que m\u00e1s importa es la forma, el estilo de juego, la mentalidad y la agresividad que tuvo el equipo. Creo que es una muestra de lo que venimos trabajando y cuando uno hace todo lo planeado, los resultados llegan solos\u201d<\/span><\/em>.<\/p>\n<p>Constantino Vaporaki: <em><span style=\"color: #ff0000;\">\u201cLa verdad que sigo pensando en ese partido con Brasil y se me pone la piel de gallina. La forma en que superamos al equipo brasilero en todas las facetas del juego y ante su gente le da una dimensi\u00f3n al triunfo por la forma en que se logr\u00f3. Nos hab\u00eda quedado la espina de los Odesur porque tambi\u00e9n hab\u00edamos sido superiores y perdimos por lo que esta era una nueva oportunidad de demostrar que no hab\u00eda sido casualidad. Diego nos prepar\u00f3 para esto y el resultado es haber ganado siete partidos de ocho con una medalla de plata y otra de oro. Somos unos privilegiados de poder vivir esto y representar a esta selecci\u00f3n\u201d<\/span><\/em>.<\/p>\n<figure id=\"attachment_10006\" aria-describedby=\"caption-attachment-10006\" style=\"width: 538px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/04\/MZL-2.jpg\"><img loading=\"lazy\" class=\"wp-image-10006   \" title=\"Selecci\u00f3n\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/04\/MZL-2.jpg\" alt=\"\" width=\"538\" height=\"358\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/04\/MZL-2.jpg 1400w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/04\/MZL-2-300x199.jpg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/04\/MZL-2-1024x682.jpg 1024w\" sizes=\"(max-width: 538px) 100vw, 538px\" \/><\/a><figcaption id=\"caption-attachment-10006\" class=\"wp-caption-text\">Credit Photo: CBFS<\/figcaption><\/figure>\n<p>Ahora el calendario marca el retorno al pa\u00eds y los \u00faltimos entrenamientos para encarar de lleno el certamen oficial con Boca Juniors. Mejor, imposible.<\/p>\n<p align=\"center\"><strong><span style=\"text-decoration: underline;\">\u00a0<\/span><\/strong><\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 1.156<\/span><span class='epvc-label'> veces le\u00edda<\/span><\/div>\n<div class=\"jwsharethis\">\nShare this: \n<br \/>\n<a href=\"mailto:?subject=Haciendo%20historia&amp;body=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fhaciendo-historia-3%2F\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/email.png\" alt=\"Share this page via Email\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.stumbleupon.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fhaciendo-historia-3%2F&amp;title=Haciendo+historia\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/su.png\" alt=\"Share this page via Stumble Upon\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/digg.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fhaciendo-historia-3%2F&amp;title=Haciendo+historia\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/digg.png\" alt=\"Share this page via Digg this\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.facebook.com\/sharer.php?u=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fhaciendo-historia-3%2F&amp;t=Haciendo+historia\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/fb.png\" alt=\"Share this page via Facebook\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/twitter.com\/intent\/tweet?text=I+like+http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fhaciendo-historia-3%2F&amp;title=Haciendo+historia\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/twitter.png\" alt=\"Share this page via Twitter\" \/>\n<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por MZL Deportes (Corresponsal LBD en Buenos Aires) Tras la medalla plateada en los Juegos Odesur, los fueguinos Alamiro y \u201cKiki\u201d Vaporaki concretaron un resultado que quedar\u00e1 en el libro dorado del Futsal AFA, adjudic\u00e1ndose la Copa de las Naciones en suelo brasilero tras comenzar 0-2 abajo y vencer 3-2 a falta de 14 segundos. &hellip; <a href=\"http:\/\/labestiadeportiva.com\/lbd\/haciendo-historia-3\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Haciendo historia<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":10005,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,4,6,60,31,1],"tags":[144,1374,117,143],"_links":{"self":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/10004"}],"collection":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/comments?post=10004"}],"version-history":[{"count":3,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/10004\/revisions"}],"predecessor-version":[{"id":10009,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/10004\/revisions\/10009"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media\/10005"}],"wp:attachment":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media?parent=10004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/categories?post=10004"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/tags?post=10004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}