{"id":10201,"date":"2014-04-09T13:58:00","date_gmt":"2014-04-09T13:58:00","guid":{"rendered":"http:\/\/labestiadeportiva.com\/lbd\/?p=10201"},"modified":"2014-04-09T13:58:00","modified_gmt":"2014-04-09T13:58:00","slug":"a-puro-talento","status":"publish","type":"post","link":"http:\/\/labestiadeportiva.com\/lbd\/a-puro-talento\/","title":{"rendered":"A puro talento"},"content":{"rendered":"<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/04\/Garro-APTP.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-10202\" title=\"Garro (APTP)\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/04\/Garro-APTP-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/04\/Garro-APTP-300x225.jpg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/04\/Garro-APTP.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>El piloto ushuaiense Lucas \u201cPaleta\u201d Garro cosech\u00f3 un enorme tercer puesto en su segunda presentaci\u00f3n dentro de la Clase 3 en La Plata y se puso a tiro del escolta en el campeonato. Por cuestiones presupuestarias peligra su participaci\u00f3n en la cita que se aproxima, a disputarse en Jun\u00edn dentro de diez d\u00edas. Fuente y foto Prensa Lucas Garro.<!--more--><\/p>\n<p>Hace dos semanas, m\u00e1s precisamente el domingo 30 de Marzo, se estuvo desarrollando la final de la segunda fecha del Turismo Pista Clase 3 en el aut\u00f3dromo \u201cRoberto Mouras\u201d de La Plata, sitio donde el representante de Ushuaia, Lucas Garro, estuvo compitiendo a bordo del VW Gol N\u00ba 77 que es atendido \u00edntegramente por Dacal Racing.<\/p>\n<p>Tras no poder girar el viernes por falta de presupuesto, el fueguino salt\u00f3 a la pista directamente el s\u00e1bado para poner a punto de la mejor forma posible a su unidad, aunque un encuentro desafortunado con otro piloto provoc\u00f3 la rotura de una mangueta, coartando la posibilidad de ultimar detalles y entrar en ritmo para la clasificaci\u00f3n.<\/p>\n<p>De esta manera y pr\u00e1cticamente sin girar sali\u00f3 a clasificar \u201cyendo a lo seguro\u201d tratando de preservar los neum\u00e1ticos. En este contexto consigui\u00f3 meterse 14\u00ba a poco m\u00e1s de dos d\u00e9cimas del sexto entrando en los tiempos de punta, teniendo en cuenta la acentuada paridad que muestra carrera tras carrera la categor\u00eda.<\/p>\n<p>Posteriormente tuvo que partir s\u00e9ptimo en una de las dos series disputadas. Lucas emprendi\u00f3 una remontada clara y prolija hasta el quinto lugar, aunque en el intento de avanzar al cuarto fue superado por tres rivales quedando octavo. Sin embargo, una buena maniobra en el giro definitivo le devolvi\u00f3 el s\u00e9ptimo puesto.<\/p>\n<p>Para la final del domingo las expectativas eran bajas por la ubicaci\u00f3n en la parrilla de salida, pero la lluvia renovaba las esperanzas. <span style=\"color: #0000ff;\">\u201cCuando vi que llovi\u00f3 pens\u00e9 en que pod\u00eda avanzar. Largu\u00e9 catorce y qued\u00e9 octavo antes del Pace Car, momento en que decid\u00ed arriesgar un poco m\u00e1s para intentar mejorar la ubicaci\u00f3n. Al no tener radio no ten\u00eda noci\u00f3n de las vueltas que faltaban por lo que me queda la espina de haber presionado un poco m\u00e1s, aunque finalmente pudimos obtener un tercer puesto incre\u00edble y subimos al podio que era lo que quer\u00eda. Adem\u00e1s me prend\u00ed en el campeonato sin haber sumado en la primera fecha as\u00ed que estamos contentos y tranquilos por lo realizado\u201d<\/span>, resumi\u00f3 Garro a modo de conclusi\u00f3n tras bajarse del podio en un trazado que le sienta bien.<\/p>\n<p>Luego de la visita al coliseo platense, el Turismo Pista se traslada al aut\u00f3dromo \u201cEusebio Marcilla\u201d de Jun\u00edn, donde el 20 del corriente mes se estar\u00e1 desarrollando la final de la tercera cita de la temporada. Lamentablemente y debido a los problemas para conseguir los recursos econ\u00f3micos necesarios, el piloto fueguino tiene muy en duda su presencia en la localidad bonaerense.<\/p>\n<p><span style=\"color: #0000ff;\">CAMPEONATO C3<\/span><br \/>\n#1 Mat\u00edas Devoto 49 puntos<br \/>\n#T-2 Pablo Vuyovich 38 puntos [+9]<br \/>\n#T-2 Jonathan Baldinelli 38 puntos [+9]<br \/>\n#4 Diego Lest\u00f3n 31 puntos [+18]<br \/>\n#5 Alberto Jaime 29 puntos [+20]<br \/>\n<span style=\"color: #ff0000;\">#T-6 LUCAS GARRO 28 puntos [+21]<\/span><\/p>\n<p>Lucas Garro y equipo agradecen a sus sponsors: Carbess, Club Lasserre, Cruciani Transporte, Constru Sec, El Diario del Fin del Mundo, Municipalidad de Ushuaia, Promat SRL, Rosana Bertone 2015, Sartini Gas, Tekno Isla y Tierra Fueguina SRL. Asimismo, a toda la gente de Tierra del Fuego, familia, amigos y a Dacal Racing por el auto que entrega en pista.<\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 2.242<\/span><span class='epvc-label'> veces le\u00edda<\/span><\/div>\n<div class=\"jwsharethis\">\nShare this: \n<br \/>\n<a href=\"mailto:?subject=A%20puro%20talento&amp;body=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fa-puro-talento%2F\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/email.png\" alt=\"Share this page via Email\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.stumbleupon.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fa-puro-talento%2F&amp;title=A+puro+talento\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/su.png\" alt=\"Share this page via Stumble Upon\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/digg.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fa-puro-talento%2F&amp;title=A+puro+talento\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/digg.png\" alt=\"Share this page via Digg this\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.facebook.com\/sharer.php?u=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fa-puro-talento%2F&amp;t=A+puro+talento\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/fb.png\" alt=\"Share this page via Facebook\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/twitter.com\/intent\/tweet?text=I+like+http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fa-puro-talento%2F&amp;title=A+puro+talento\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/twitter.png\" alt=\"Share this page via Twitter\" \/>\n<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El piloto ushuaiense Lucas \u201cPaleta\u201d Garro cosech\u00f3 un enorme tercer puesto en su segunda presentaci\u00f3n dentro de la Clase 3 en La Plata y se puso a tiro del escolta en el campeonato. Por cuestiones presupuestarias peligra su participaci\u00f3n en la cita que se aproxima, a disputarse en Jun\u00edn dentro de diez d\u00edas. Fuente y &hellip; <a href=\"http:\/\/labestiadeportiva.com\/lbd\/a-puro-talento\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">A puro talento<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":10202,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,6,1],"tags":[86,151,808],"_links":{"self":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/10201"}],"collection":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/comments?post=10201"}],"version-history":[{"count":1,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/10201\/revisions"}],"predecessor-version":[{"id":10203,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/10201\/revisions\/10203"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media\/10202"}],"wp:attachment":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media?parent=10201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/categories?post=10201"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/tags?post=10201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}