{"id":16264,"date":"2015-07-01T14:14:42","date_gmt":"2015-07-01T17:14:42","guid":{"rendered":"http:\/\/labestiadeportiva.com\/lbd\/?p=16264"},"modified":"2015-07-01T14:14:42","modified_gmt":"2015-07-01T17:14:42","slug":"argentina-vapuleo-a-paraguay-y-definira-con-chile","status":"publish","type":"post","link":"http:\/\/labestiadeportiva.com\/lbd\/argentina-vapuleo-a-paraguay-y-definira-con-chile\/","title":{"rendered":"Argentina vapule\u00f3 a Paraguay y definir\u00e1 con Chile"},"content":{"rendered":"<p><strong><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/07\/Argentina1.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-16265\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/07\/Argentina1-300x169.jpg\" alt=\"Argentina1\" width=\"300\" height=\"169\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/07\/Argentina1-300x169.jpg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/07\/Argentina1.jpg 630w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Por Mart\u00edn Tinka Velasco (Corresponsal LBD en C\u00f3rdoba). Con goles de Rojo, Pastore, Di Mar\u00eda (x2), Ag\u00fcero e Higua\u00edn, la Albiceleste venci\u00f3 6-1 al conjunto de Ram\u00f3n D\u00edaz, que descont\u00f3 a trav\u00e9s de Barrios. El s\u00e1bado, desde las 17, buscar\u00e1 ser campe\u00f3n de Am\u00e9rica ante el conjunto local, que un d\u00eda antes elimin\u00f3 a Per\u00fa.<\/strong><!--more--><\/p>\n<p>Si a alguno le hab\u00edan quedado dudas del potencial que tiene la selecci\u00f3n de Martino, anoche debi\u00f3 confirmar que la idea del DT est\u00e1 siendo interpretada a la perfecci\u00f3n por los jugadores. Con una gran demostraci\u00f3n de f\u00fatbol y juego asociado, Argentina tuvo un partido casi perfecto y avanz\u00f3 a la definici\u00f3n de la Copa Am\u00e9rica 2015.<\/p>\n<p>En la primera mitad fue Marcos Rojo quien abri\u00f3 el marcador, a los 14&#8242;, tras un tiro libre desde el sector izquierdo. 13 minutos m\u00e1s tarde, Messi habilit\u00f3 a Pastore, quien acomod\u00f3 pelota y cuerpo para definir cruzado ante la salida del arquero Villar. Era 2-0, dominio y tranquilidad. Pero Otamendi pec\u00f3 de inocente, busc\u00f3 un pase llovido al medio y Paraguay descont\u00f3 por el ingresado Lucas Barrios, cuando se mor\u00eda la etapa.<\/p>\n<p>Apenas comenzado el complemento, el Flaco Pastore, la figura de la noche, le dio un pase de crack a \u00c1ngel Di Mar\u00eda, que la toc\u00f3 para el 3-1 parcial. En 53`, otra vez el zurdo de Manchester United se anot\u00f3 en el marcador, con el arco solo tras una excelente acci\u00f3n de Messi y rebote del 1 rival. Faltando 10&#8242; lleg\u00f3 el tanto de Sergio Ag\u00fcero, de cabeza y cerrando la goleada apareci\u00f3 Gonzalo Higua\u00edn, con olfato de goleador para el 6-1 definitivo.<\/p>\n<p>Salvo algunos errores puntuales, como el fallo de Otamendi en el descuento Guaran\u00ed, Argentina mostr\u00f3 a la perfecci\u00f3n el modelo de juego que pretende desarrollar el entrenador. Salida desde abajo, control del mediocampo, saltear l\u00edneas con pases profundos y ataque con muchos jugadores, entre otros fundamentos, se vieron reflejados en la noche de ayer.<\/p>\n<p>Con este repertorio, m\u00e1s la cuota de sacrificio que requiere disputar una final, la selecci\u00f3n nacional buscar\u00e1 el pr\u00f3ximo s\u00e1bado, a partir de las 17, hacerle frente e imponerse a Chile, otro conjunto que a lo largo de la Copa dej\u00f3 ver su buen funcionamiento. Justamente los trasandinos, el lunes, sufrieron pero dejaron en el camino a Per\u00fa por 2-1.<\/p>\n<p>Los goles argentinos:<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/ILUfdwpqy48\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 1.348<\/span><span class='epvc-label'> veces le\u00edda<\/span><\/div>\n<div class=\"jwsharethis\">\nShare this: \n<br \/>\n<a href=\"mailto:?subject=Argentina%20vapule%C3%B3%20a%20Paraguay%20y%20definir%C3%A1%20con%20Chile&amp;body=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fargentina-vapuleo-a-paraguay-y-definira-con-chile%2F\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/email.png\" alt=\"Share this page via Email\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.stumbleupon.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fargentina-vapuleo-a-paraguay-y-definira-con-chile%2F&amp;title=Argentina+vapule%C3%B3+a+Paraguay+y+definir%C3%A1+con+Chile\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/su.png\" alt=\"Share this page via Stumble Upon\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/digg.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fargentina-vapuleo-a-paraguay-y-definira-con-chile%2F&amp;title=Argentina+vapule%C3%B3+a+Paraguay+y+definir%C3%A1+con+Chile\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/digg.png\" alt=\"Share this page via Digg this\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.facebook.com\/sharer.php?u=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fargentina-vapuleo-a-paraguay-y-definira-con-chile%2F&amp;t=Argentina+vapule%C3%B3+a+Paraguay+y+definir%C3%A1+con+Chile\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/fb.png\" alt=\"Share this page via Facebook\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/twitter.com\/intent\/tweet?text=I+like+http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fargentina-vapuleo-a-paraguay-y-definira-con-chile%2F&amp;title=Argentina+vapule%C3%B3+a+Paraguay+y+definir%C3%A1+con+Chile\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/twitter.png\" alt=\"Share this page via Twitter\" \/>\n<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por Mart\u00edn Tinka Velasco (Corresponsal LBD en C\u00f3rdoba). Con goles de Rojo, Pastore, Di Mar\u00eda (x2), Ag\u00fcero e Higua\u00edn, la Albiceleste venci\u00f3 6-1 al conjunto de Ram\u00f3n D\u00edaz, que descont\u00f3 a trav\u00e9s de Barrios. El s\u00e1bado, desde las 17, buscar\u00e1 ser campe\u00f3n de Am\u00e9rica ante el conjunto local, que un d\u00eda antes elimin\u00f3 a Per\u00fa. &hellip; <a href=\"http:\/\/labestiadeportiva.com\/lbd\/argentina-vapuleo-a-paraguay-y-definira-con-chile\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Argentina vapule\u00f3 a Paraguay y definir\u00e1 con Chile<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":16265,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2194],"tags":[144,842,2195,233,1801,1938,90,332],"_links":{"self":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/16264"}],"collection":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/comments?post=16264"}],"version-history":[{"count":1,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/16264\/revisions"}],"predecessor-version":[{"id":16266,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/16264\/revisions\/16266"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media\/16265"}],"wp:attachment":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media?parent=16264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/categories?post=16264"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/tags?post=16264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}