{"id":17328,"date":"2015-09-22T01:39:38","date_gmt":"2015-09-22T04:39:38","guid":{"rendered":"http:\/\/labestiadeportiva.com\/lbd\/?p=17328"},"modified":"2015-09-22T01:39:38","modified_gmt":"2015-09-22T04:39:38","slug":"copa-davis-fin-del-sueno","status":"publish","type":"post","link":"http:\/\/labestiadeportiva.com\/lbd\/copa-davis-fin-del-sueno\/","title":{"rendered":"Copa Davis: Fin del sue\u00f1o"},"content":{"rendered":"<p>Por Mat\u00edas Pouso (Corresponsal LBD en CABA)<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/09\/0921-Belgium.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-17329\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/09\/0921-Belgium-300x210.jpg\" alt=\"Steve Darcis\" width=\"300\" height=\"210\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/09\/0921-Belgium-300x210.jpg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/09\/0921-Belgium.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>A pesar de haber estado cerca del batacazo, el equipo argentino fue eliminado por su par belga y mirar\u00e1 desde afuera la final de la Copa Davis. A pesar de la derrota, fue un gran a\u00f1o para este equipo que el mi\u00e9rcoles conocer\u00e1 a su primer rival del 2016.<!--more--><\/p>\n<p>B\u00e9lgica alcanz\u00f3 la segunda final de Copa Davis de su historia tras derrotar por 3-2 a la Argentina, los europeos, que no llegaban a la serie decisiva por la Ensaladera desde 1904, remontaron el 1-2 con que cerr\u00f3 la jornada del s\u00e1bado.<\/p>\n<p>As\u00ed, y tras superar al conjunto albiceleste, recibir\u00e1n a Gran Breta\u00f1a del 27 al 29 de noviembre buscando el primer t\u00edtulo de su historia.<\/p>\n<p>El domingo a primera hora, David Goffin cont\u00f3 con la fortuna de enfrentar a Diego Schwartzman debido a la baja de Leonardo Mayer, el correntino no soport\u00f3 la sobrecarga f\u00edsica de los partidos del viernes y el s\u00e1bado.<\/p>\n<p>El triunfo del n\u00famero 15 del mundo fue por un contundente 6-3, 6-2 y 6-1, haciendo de su saque el arma principal de su juego.<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/09\/AAT_130.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-17330\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/09\/AAT_130-300x199.jpg\" alt=\"AAT_130\" width=\"300\" height=\"199\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/09\/AAT_130-300x199.jpg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/09\/AAT_130-1024x680.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Goffin control\u00f3 los embates de Schwartzman conectando 11 aces, qued\u00e1ndose con el 86% de los puntos jugados con su primer servicio y sin ceder siquiera un juego de saque en todo el encuentro.<\/p>\n<p>De la misma manera, su devoluci\u00f3n fue contundente, llegando a controlar casi la mitad (49%) de los puntos en que el argentino puso la pelota en juego.<\/p>\n<p>De esta manera, y luego de 1 hora y 47 minutos de juego, puso la paridad en la semifinal disputada en Bruselas.<\/p>\n<p>Minutos despu\u00e9s, los encargados de decidir al finalista ser\u00edan Steve Darcis y Federico Delbonis. El belga, que compiti\u00f3 durante los tres d\u00edas, se sobrepuso al desgaste f\u00edsico acumulado para lograr el pasaje hist\u00f3rico luego de un partido de ida y vuelta, tanto en el resultado como en lo an\u00edmico.<\/p>\n<p>En un encuentro que super\u00f3 las tres horas, el nacido en Lieja impuso su regularidad ganando el 77% de los puntos con su primer saque y quebrando en cuatro ocasiones el servicio del argentino.<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/09\/Delbonis.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-17331\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/09\/Delbonis-300x200.jpg\" alt=\"Delbonis\" width=\"300\" height=\"200\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/09\/Delbonis-300x200.jpg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/09\/Delbonis.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>La actuaci\u00f3n de Delbonis fue muy buena, conect\u00f3 nueve aces y 58 tiros ganadores contra cuatro y 43 del belga; sin embargo, el europeo golpe\u00f3 en los momentos importantes de cada set.<\/p>\n<p>En el primero todos los puntos fueron cortos, a un m\u00e1ximo de dos o tres intercambios, hasta que el marcador qued\u00f3 igualado en tres, ah\u00ed Delbonis cometi\u00f3 una doble falta, Darcis quebr\u00f3 y se adelant\u00f3 4-3, cada uno ganar\u00eda sus respectivos saques y el parcial quedar\u00eda 6-4 para el belga.<\/p>\n<p>El azule\u00f1o reaccion\u00f3 en el segundo parcial ajustando la devoluci\u00f3n y se adelant\u00f3 un par de metros en la cancha, eso le permiti\u00f3 levantar un 15-40 en contra para ponerse 3-2, luego quebr\u00f3 para adelantarse 4-2 y cerr\u00f3 el set con otra ruptura para sellar el 6-2.<\/p>\n<p>Darcis volvi\u00f3 en s\u00ed en el tercer set, comenz\u00f3 a dominar el juego con pelotas bajas sobre el rev\u00e9s del argentino, as\u00ed impuso sus condiciones y se llev\u00f3 el set por 7-5.<\/p>\n<p>En el cuarto y definitivo, se vivi\u00f3 el momento m\u00e1s emotivo, con Darcis al frente casi siempre (tuvo dos match points con su servicio cuando sacaba 5-4) y Delbonis dando muestras de un enorme coraje para salvar cada situaci\u00f3n en una superficie que no favoreci\u00f3 para nada su juego.<\/p>\n<p>El argentino estir\u00f3 la agon\u00eda hasta el tie break y all\u00ed cay\u00f3 sin atenuantes por 7-3, lo que desat\u00f3 el festejo el banco europeo y la desaz\u00f3n del lado argentino.<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/09\/AAT_149.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-17332\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/09\/AAT_149-300x200.jpg\" alt=\"AAT_149\" width=\"300\" height=\"200\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/09\/AAT_149-300x200.jpg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/09\/AAT_149-1024x681.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Una vez m\u00e1s, la Copa Davis se alej\u00f3 de la ilusi\u00f3n argentina. Esta vez la despedida fue ante un adversario superior, que aprovech\u00f3 la ventaja de la local\u00eda, que eligi\u00f3 la superficie que m\u00e1s le convino, y que adem\u00e1s cont\u00f3 con David Goffin, n\u00famero 15 del mundo, en \u00f3ptima forma.<\/p>\n<p>A pesar de las adversidades y de las limitaciones, la Argentina volvi\u00f3 a quedar dentro de los cuatro mejores de la Davis, como ya lo hizo diez veces en los \u00faltimos 14 a\u00f1os.<\/p>\n<p>La derrota fue dura para los comandados por Daniel Orsanic, sobre todo porque se estuvo cerca del triunfo, pero antes de la serie se sab\u00eda que ser\u00eda un fin de semana de cruces parejos y resultados cerrados, con margen m\u00ednimo para alguno de los dos lados; en esos detalles, B\u00e9lgica sac\u00f3 una leve luz de ventaja.<\/p>\n<p>En cuanto al futuro del plantel, no se esperan grandes cambios. Queda pr\u00e1cticamente medio a\u00f1o hasta la pr\u00f3xima serie, por lo que habr\u00e1 que ver c\u00f3mo siguen las carreras de Mayer, Delbonis, Schwartzman y Berlocq y c\u00f3mo llegar\u00edan a esa cita.<\/p>\n<p>Y pensando por fuera del equipo, habr\u00e1 que esperar para saber c\u00f3mo se encuentran f\u00edsica y ten\u00edsticamente Juan Mart\u00edn del Potro y Juan M\u00f3naco.<\/p>\n<p>Este mi\u00e9rcoles se sortear\u00e1n los cruces para 2016, Argentina ser\u00e1 cabeza de serie y sus presuntos rivales en el debut ser\u00e1n Estados Unidos (de local); Canad\u00e1, Croacia, Italia, Alemania o Kazajst\u00e1n (de visitante), y por \u00faltimo Polonia o Jap\u00f3n (definici\u00f3n de sede por sorteo).<\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 1.114<\/span><span class='epvc-label'> veces le\u00edda<\/span><\/div>\n<div class=\"jwsharethis\">\nShare this: \n<br \/>\n<a href=\"mailto:?subject=Copa%20Davis%3A%20Fin%20del%20sue%C3%B1o&amp;body=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fcopa-davis-fin-del-sueno%2F\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/email.png\" alt=\"Share this page via Email\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.stumbleupon.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fcopa-davis-fin-del-sueno%2F&amp;title=Copa+Davis%3A+Fin+del+sue%C3%B1o\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/su.png\" alt=\"Share this page via Stumble Upon\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/digg.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fcopa-davis-fin-del-sueno%2F&amp;title=Copa+Davis%3A+Fin+del+sue%C3%B1o\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/digg.png\" alt=\"Share this page via Digg this\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.facebook.com\/sharer.php?u=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fcopa-davis-fin-del-sueno%2F&amp;t=Copa+Davis%3A+Fin+del+sue%C3%B1o\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/fb.png\" alt=\"Share this page via Facebook\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/twitter.com\/intent\/tweet?text=I+like+http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fcopa-davis-fin-del-sueno%2F&amp;title=Copa+Davis%3A+Fin+del+sue%C3%B1o\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/twitter.png\" alt=\"Share this page via Twitter\" \/>\n<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por Mat\u00edas Pouso (Corresponsal LBD en CABA) A pesar de haber estado cerca del batacazo, el equipo argentino fue eliminado por su par belga y mirar\u00e1 desde afuera la final de la Copa Davis. A pesar de la derrota, fue un gran a\u00f1o para este equipo que el mi\u00e9rcoles conocer\u00e1 a su primer rival del &hellip; <a href=\"http:\/\/labestiadeportiva.com\/lbd\/copa-davis-fin-del-sueno\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Copa Davis: Fin del sue\u00f1o<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":17329,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,1,39],"tags":[2352,40,4835],"_links":{"self":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/17328"}],"collection":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/comments?post=17328"}],"version-history":[{"count":1,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/17328\/revisions"}],"predecessor-version":[{"id":17333,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/17328\/revisions\/17333"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media\/17329"}],"wp:attachment":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media?parent=17328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/categories?post=17328"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/tags?post=17328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}