{"id":18912,"date":"2016-02-16T10:36:25","date_gmt":"2016-02-16T13:36:25","guid":{"rendered":"http:\/\/labestiadeportiva.com\/lbd\/?p=18912"},"modified":"2016-02-16T11:50:33","modified_gmt":"2016-02-16T14:50:33","slug":"primera-division-capitulo-2","status":"publish","type":"post","link":"http:\/\/labestiadeportiva.com\/lbd\/primera-division-capitulo-2\/","title":{"rendered":"Primera Divisi\u00f3n, cap\u00edtulo 2"},"content":{"rendered":"<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/02\/Belgrano.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-18913\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/02\/Belgrano-300x169.jpg\" alt=\"Belgrano\" width=\"300\" height=\"169\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/02\/Belgrano-300x169.jpg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/02\/Belgrano.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><strong>Por Mart\u00edn Velasco (Corresponsal LBD en C\u00f3rdoba). Para no perderle pisada a la m\u00e1xima categor\u00eda del f\u00fatbol argentino, en La Bestia vuelve el repaso con lo m\u00e1s importante de cada jornada. En este caso, destacando el\u00a0gran triunfo de Belgrano sobre River, la ca\u00edda de Boca como local y una nueva victoria de Central en el cl\u00e1sico rosarino. Pasen y lean&#8230;<\/strong><!--more--><\/p>\n<p>Por la zona 1, quiz\u00e1s la m\u00e1s complicada debido a los equipos que la integran, hubo cruces extremadamente atractivos. Por un lado, con el triunfo ag\u00f3nico de San Lorenzo 2-1 sobre Sarmiento, que se hab\u00eda puesto en ventaja y no logr\u00f3 sostener el ritmo. El Cicl\u00f3n sigue con su buen andar tras la goleada entre semana ante Boca por la Supercopa Argentina y se perfila como uno de los candidatos a pelear el t\u00edtulo.<\/p>\n<p>Ya en domingo, Rosario Central celebr\u00f3 su quinto cl\u00e1sico ganado de manera consecutiva a su eterno rival, Newell`s Old Boys, que adem\u00e1s sufri\u00f3 el alejamiento de su entrenador, Lucas Bernardi. Los goles para el 2-0 final del Canalla fueron anotados por Larrondo y Marco Ruben, tras una gran jugada colectiva. El derby rosarino fue el encuentro interzonal de la fecha.<\/p>\n<p>River, en tanto, viaj\u00f3 a C\u00f3rdoba con las expectativas renovadas luego de vencer abultadamente a Quilmes en la primera jornada. En frente estaba Belgrano, un viejo conocido. Con un tr\u00e1mite parejo lleg\u00f3 la primera alegr\u00eda, con un remate desde afuera del \u00e1rea de Iv\u00e1n Etevenaux. Al rato nom\u00e1s, Jorge Vel\u00e1zquez defini\u00f3 de manera exquisita y puso el 2-0 parcial, pero Nicol\u00e1s Domingo, desde afuera del \u00e1rea, descont\u00f3. Antes del cierre de la primera etapa, nuevamente Etevenaux adelant\u00f3 al Pirata, que debi\u00f3 sufrir hasta el final por un nuevo gol de River, esta vez a trav\u00e9s del uruguayo Iv\u00e1n Alonso.<\/p>\n<p>La zona 2, por su parte, tuvo como protagonistas a Boca y Atl\u00e9tico Tucum\u00e1n. El Xeneize, golpeado por la ca\u00edda con San Lorenzo, tuvo en cancha a un equipo repleto de jugadores con experiencia pero igualmente volvi\u00f3 a jugar mal y cay\u00f3 1-0 ante el Decano, que lleg\u00f3 al gol por Leandro Gonz\u00e1lez, luego de ser asistido por la Pulga Luis Rodr\u00edguez. Tras el duelo jugado en La Bombonera, la continuidad de Rodolfo Arruabarrena qued\u00f3 en duda, pero el DT manifest\u00f3 tener fuerzas para continuar en el cargo.<\/p>\n<p>Racing, otro de los que seguramente pelear\u00e1 hasta el final, tuvo dos veces el marcador a su favor pero pec\u00f3 de errores defensivos e igual\u00f3 2-2 con San Mart\u00edn de San Juan, en el Cilindro de Avellaneda, mientras que Lan\u00fas, con dos de Pepe Sand, se lo dio vuelta a Defensa y Justicia.<\/p>\n<p>Ahora si, todas las estad\u00edsticas:<\/p>\n<h2>RESULTADOS<\/h2>\n<p><strong>Viernes 12 de febrero<\/strong><br \/>\nUni\u00f3n <strong>3<\/strong> (Claudio Ria\u00f1o -2- y V\u00edctor Malcorra) &#8211; Temperley <strong>0<\/strong><br \/>\nArsenal <strong>3<\/strong> (Juan S\u00e1nchez Sotelo -2- \u00a0y Gabriel Sanabria) &#8211; Banfield <strong>1<\/strong> (Jonathan Bottinelli e\/c)<br \/>\nQuilmes <strong>2<\/strong> (Ezequiel Rescaldani -2-) &#8211; Col\u00f3n <strong>4<\/strong> (Franco Mazurek, Pablo Ledesma -2- y Nicol\u00e1s Silva)<br \/>\nGodoy Cruz <strong>1<\/strong> (Santiago Garc\u00eda) &#8211; Independiente <strong>1<\/strong> (Germ\u00e1n Denis)<\/p>\n<p><strong>S\u00e1bado 13 de febrero<\/strong><br \/>\nSan Lorenzo <strong>2<\/strong> (N\u00e9stor Ortigoza y Pablo Barrientos) &#8211; Sarmiento <strong>1<\/strong> (Walter Busse)<br \/>\nAldosivi <strong>3<\/strong> (Jonathan Galv\u00e1n, Cristian Llama y Gast\u00f3n D\u00edaz) &#8211; Argentinos <strong>2<\/strong> (Federico Ins\u00faa y Lautaro Rinaldi)<br \/>\nAtl\u00e9tico de Rafaela <strong>0<\/strong> &#8211; Estudiantes <strong>1<\/strong> (Lucas Viatri)<br \/>\nV\u00e9lez <strong>2<\/strong> (Cristian Nasuti y Maximiliano Romero) &#8211; Olimpo <strong>1<\/strong> (Walter Acu\u00f1a)<br \/>\nRacing <strong>2<\/strong> (Gustavo Bou y \u00d3scar Romero) &#8211; San Mart\u00edn <strong>2<\/strong> (Daniel Gonz\u00e1lez y Javier Toledo)<\/p>\n<p><strong>Domingo 14 de febrero<\/strong><br \/>\nLan\u00fas <strong>2<\/strong> (Jos\u00e9 Sand -2-) &#8211; Defensa y Justicia <strong>1<\/strong> (Fabi\u00e1n Bordagaray)<br \/>\nRosario Central <strong>2<\/strong> (Marcelo Larrondo y Marco Ruben) &#8211; Newell&#8217;s <strong>0<br \/>\n<\/strong>Gimnasia <strong>3<\/strong> (Franco Niell, Lorenzo Faravelli y Walter Bou) &#8211; Patronato <strong>2<\/strong> (Mat\u00edas Garrido -2-)<br \/>\nBoca <strong>0<\/strong> &#8211; Atl\u00e9tico Tucum\u00e1n <strong>1<\/strong> (Leandro Gonz\u00e1lez)<br \/>\nBelgrano <strong>3<\/strong> (Iv\u00e1n Etevenaux -2- y Jorge Vel\u00e1zquez) &#8211; River <strong>2<\/strong> (Nicol\u00e1s Domingo e Iv\u00e1n Alonso)<\/p>\n<p><strong>Postergado<\/strong><br \/>\nTigre-Hurac\u00e1n<\/p>\n<h2>POSICIONES<\/h2>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/02\/zona1.jpg\"><img loading=\"lazy\" class=\"aligncenter wp-image-18915 size-full\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/02\/zona1.jpg\" alt=\"zona1\" width=\"1017\" height=\"491\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/02\/zona1.jpg 1017w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/02\/zona1-300x145.jpg 300w\" sizes=\"(max-width: 1017px) 100vw, 1017px\" \/><\/a><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/02\/zona1.jpg\"><br \/>\n<\/a><br \/>\n<a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/02\/zona2.jpg\"><img loading=\"lazy\" class=\"aligncenter wp-image-18916 size-full\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/02\/zona2.jpg\" alt=\"zona2\" width=\"1021\" height=\"488\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/02\/zona2.jpg 1021w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/02\/zona2-300x143.jpg 300w\" sizes=\"(max-width: 1021px) 100vw, 1021px\" \/><\/a><\/p>\n<h2>SHOW DE GOLES<\/h2>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/bcAEEtDM0-4\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h2>PR\u00d3XIMA FECHA<\/h2>\n<p><strong>Martes 16 de febrero:<\/strong><\/p>\n<p>17.00: Banfield-Quilmes, Pablo D\u00edaz<br \/>\n19.15: Hurac\u00e1n-Aldosivi de Mar del Plata, Dar\u00edo Herrera<br \/>\n19.15:\u00a0Olimpo-San Lorenzo de Almagro, N\u00e9stor Pitana<br \/>\n21.30: Argentinos Juniors-V\u00e9lez Sarsfield, Fernando Rapallini<\/p>\n<p><strong>Mi\u00e9rcoles 17 de febrero:<\/strong><\/p>\n<p>17.00: Defensa y Justicia-Atl\u00e9tico de Rafaela, Mauro Vigliano<br \/>\n17.00:\u00a0Newell&#8217;s Old Boys-Racing Club, Juan Pablo Pompei<br \/>\n19.15:\u00a0Independiente-Rosario Central, Jorge Bali\u00f1o<br \/>\n19.15:\u00a0Patronato-Arsenal, Nicol\u00e1s Lamolina<br \/>\n21.15: San Mart\u00edn de San Juan-Boca Juniors, Silvio Trucco<br \/>\n21.30: Sarmiento-Gimnasia y Esgrima La Plata, Pablo Lunati<\/p>\n<p><strong>Jueves 18 de febrero:<\/strong><\/p>\n<p>17.00: Estudiantes-Tigre, en la cancha de Arsenal, Patricio Loustau<br \/>\n19.00: Col\u00f3n-Belgrano de C\u00f3rdoba, Federico Beligoy<br \/>\n19.00: Temperley-Lan\u00fas, Diego Abal<br \/>\n21.15: River Plate-Godoy Cruz de Mendoza, Germ\u00e1n Delfino<br \/>\n21.15: Atl\u00e9tico Tucum\u00e1n-Uni\u00f3n, Fernando Espinoza.<\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 1.309<\/span><span class='epvc-label'> veces le\u00edda<\/span><\/div>\n<div class=\"jwsharethis\">\nShare this: \n<br \/>\n<a href=\"mailto:?subject=Primera%20Divisi%C3%B3n%2C%20cap%C3%ADtulo%202&amp;body=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fprimera-division-capitulo-2%2F\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/email.png\" alt=\"Share this page via Email\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.stumbleupon.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fprimera-division-capitulo-2%2F&amp;title=Primera+Divisi%C3%B3n%2C+cap%C3%ADtulo+2\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/su.png\" alt=\"Share this page via Stumble Upon\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/digg.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fprimera-division-capitulo-2%2F&amp;title=Primera+Divisi%C3%B3n%2C+cap%C3%ADtulo+2\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/digg.png\" alt=\"Share this page via Digg this\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.facebook.com\/sharer.php?u=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fprimera-division-capitulo-2%2F&amp;t=Primera+Divisi%C3%B3n%2C+cap%C3%ADtulo+2\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/fb.png\" alt=\"Share this page via Facebook\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/twitter.com\/intent\/tweet?text=I+like+http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fprimera-division-capitulo-2%2F&amp;title=Primera+Divisi%C3%B3n%2C+cap%C3%ADtulo+2\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/twitter.png\" alt=\"Share this page via Twitter\" \/>\n<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por Mart\u00edn Velasco (Corresponsal LBD en C\u00f3rdoba). Para no perderle pisada a la m\u00e1xima categor\u00eda del f\u00fatbol argentino, en La Bestia vuelve el repaso con lo m\u00e1s importante de cada jornada. En este caso, destacando el\u00a0gran triunfo de Belgrano sobre River, la ca\u00edda de Boca como local y una nueva victoria de Central en el &hellip; <a href=\"http:\/\/labestiadeportiva.com\/lbd\/primera-division-capitulo-2\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Primera Divisi\u00f3n, cap\u00edtulo 2<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":18913,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6,1987,1],"tags":[1086,1230,245,1801,1830,2051,1208],"_links":{"self":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/18912"}],"collection":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/comments?post=18912"}],"version-history":[{"count":4,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/18912\/revisions"}],"predecessor-version":[{"id":18919,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/18912\/revisions\/18919"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media\/18913"}],"wp:attachment":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media?parent=18912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/categories?post=18912"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/tags?post=18912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}