{"id":21275,"date":"2016-08-22T12:38:32","date_gmt":"2016-08-22T15:38:32","guid":{"rendered":"http:\/\/labestiadeportiva.com\/lbd\/?p=21275"},"modified":"2016-08-22T12:38:32","modified_gmt":"2016-08-22T15:38:32","slug":"primera-division-dias-y-horarios-de-la-fecha-1","status":"publish","type":"post","link":"http:\/\/labestiadeportiva.com\/lbd\/primera-division-dias-y-horarios-de-la-fecha-1\/","title":{"rendered":"Primera Divisi\u00f3n: d\u00edas y horarios de la fecha 1"},"content":{"rendered":"<p><strong><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/08\/Belgrano-Independiente.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-21276\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/08\/Belgrano-Independiente-300x224.jpg\" alt=\"Belgrano-Independiente\" width=\"300\" height=\"224\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/08\/Belgrano-Independiente-300x224.jpg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/08\/Belgrano-Independiente.jpg 590w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Por Mart\u00edn Velasco (Corresponsal LBD en C\u00f3rdoba). Tras el largo parate por los Juegos Ol\u00edmpicos, la m\u00e1xima categor\u00eda del f\u00fatbol argentino tendr\u00e1 su inicio el pr\u00f3ximo fin de semana.\u00a0Entre los representantes cordobeses, Talleres jugar\u00e1 el s\u00e1bado y Belgrano el domingo.<\/strong><!--more--><\/p>\n<p>Se acab\u00f3 la espera para todos los amantes del deporte m\u00e1s lindo del mundo. Argentina volver\u00e1 a tener a partir del fin de semana su campeonato local, con equipos reforzados e ilusiones renovadas para cada uno de los planteles.<\/p>\n<p>La apertura se dar\u00e1 el viernes, desde las 19, con el duelo entre Sarmiento y Arsenal. El s\u00e1bado, en tanto, volver\u00e1 a jugar en Primera Divisi\u00f3n tras largos a\u00f1os en el ascenso Talleres, que visitar\u00e1 desde las 18 al Racing de Claudio Ubeda, DT interino hasta tanto se oficialice el reemplazante del despedido Sava.<\/p>\n<p>El domingo tendr\u00e1 varios platos fuertes. Por un lado, a partir de las 16 Belgrano recibir\u00e1 a Independiente en el Estadio Mario Alberto Kempes. A su vez, River iniciar\u00e1 su torneo en el horario central de las 18, contra Banfield y en el Monumental. En tanto, Boca viajar\u00e1 a la casa del \u00faltimo campe\u00f3n, Lan\u00fas, en el duelo m\u00e1s atractivo de la jornada, que comenzar\u00e1 a las 20.<\/p>\n<p>Te dejamos el listado completo con cada uno de los encuentros:<\/p>\n<p><strong>Viernes 26 de agosto<\/strong><\/p>\n<p>Sarmiento <strong>vs.<\/strong> Arsenal<br \/>\nHora: 19<\/p>\n<p>Godoy Cruz <strong>vs.<\/strong> Hurac\u00e1n<br \/>\nHora: 21.15<\/p>\n<p><strong>S\u00e1bado 27 de agosto<\/strong><\/p>\n<p>Gimnasia (LP) <strong>vs.<\/strong> V\u00e9lez<br \/>\nHora: 14<\/p>\n<p>Rosario Central <strong>vs.<\/strong> Defensa y Justicia<br \/>\nHora: 16<\/p>\n<p>Atl\u00e9tico Tucum\u00e1n <strong>vs.<\/strong> Atl\u00e9tico de Rafaela<br \/>\nHora: 16<\/p>\n<p>Racing <strong>vs.<\/strong> Talleres (Cba)<br \/>\nHora: 18<\/p>\n<p>San Lorenzo <strong>vs.<\/strong> San Mart\u00edn (SJ)<br \/>\nHora: 20<\/p>\n<p><strong>Domingo 28 de agosto<\/strong><\/p>\n<p>Tigre <strong>vs.<\/strong> Estudiantes (LP)<br \/>\nHora: 14<\/p>\n<p>Quilmes <strong>vs.<\/strong> Newell&#8217;s<br \/>\nHora: 14<\/p>\n<p>Belgrano <strong>vs.<\/strong> Independiente<br \/>\nHora: 16<\/p>\n<p>Uni\u00f3n <strong>vs.<\/strong> Olimpo<br \/>\nHora: 16<\/p>\n<p>River <strong>vs.<\/strong> Banfield<br \/>\nHora: 18<\/p>\n<p>Lan\u00fas <strong>vs.<\/strong> Boca<br \/>\nHora: 20<\/p>\n<p><strong>Lunes 29 de agosto<\/strong><\/p>\n<p>Aldosivi <strong>vs.<\/strong> Col\u00f3n<br \/>\nHora: 19<\/p>\n<p>Temperley <strong>vs.<\/strong> Patronato<br \/>\nHora: 21.15.<\/p>\n<p>&nbsp;<\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 1.498<\/span><span class='epvc-label'> veces le\u00edda<\/span><\/div>\n<div class=\"jwsharethis\">\nShare this: \n<br \/>\n<a href=\"mailto:?subject=Primera%20Divisi%C3%B3n%3A%20d%C3%ADas%20y%20horarios%20de%20la%20fecha%201&amp;body=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fprimera-division-dias-y-horarios-de-la-fecha-1%2F\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/email.png\" alt=\"Share this page via Email\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.stumbleupon.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fprimera-division-dias-y-horarios-de-la-fecha-1%2F&amp;title=Primera+Divisi%C3%B3n%3A+d%C3%ADas+y+horarios+de+la+fecha+1\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/su.png\" alt=\"Share this page via Stumble Upon\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/digg.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fprimera-division-dias-y-horarios-de-la-fecha-1%2F&amp;title=Primera+Divisi%C3%B3n%3A+d%C3%ADas+y+horarios+de+la+fecha+1\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/digg.png\" alt=\"Share this page via Digg this\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.facebook.com\/sharer.php?u=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fprimera-division-dias-y-horarios-de-la-fecha-1%2F&amp;t=Primera+Divisi%C3%B3n%3A+d%C3%ADas+y+horarios+de+la+fecha+1\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/fb.png\" alt=\"Share this page via Facebook\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/twitter.com\/intent\/tweet?text=I+like+http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fprimera-division-dias-y-horarios-de-la-fecha-1%2F&amp;title=Primera+Divisi%C3%B3n%3A+d%C3%ADas+y+horarios+de+la+fecha+1\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/twitter.png\" alt=\"Share this page via Twitter\" \/>\n<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por Mart\u00edn Velasco (Corresponsal LBD en C\u00f3rdoba). Tras el largo parate por los Juegos Ol\u00edmpicos, la m\u00e1xima categor\u00eda del f\u00fatbol argentino tendr\u00e1 su inicio el pr\u00f3ximo fin de semana.\u00a0Entre los representantes cordobeses, Talleres jugar\u00e1 el s\u00e1bado y Belgrano el domingo. 1.498 veces le\u00edda Share this:<\/p>\n","protected":false},"author":1,"featured_media":21276,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1987],"tags":[1086,1230,245,809,1803,61,2781,798,2196,1208,1154],"_links":{"self":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/21275"}],"collection":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/comments?post=21275"}],"version-history":[{"count":1,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/21275\/revisions"}],"predecessor-version":[{"id":21277,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/21275\/revisions\/21277"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media\/21276"}],"wp:attachment":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media?parent=21275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/categories?post=21275"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/tags?post=21275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}