{"id":21439,"date":"2016-09-06T13:05:05","date_gmt":"2016-09-06T16:05:05","guid":{"rendered":"http:\/\/labestiadeportiva.com\/lbd\/?p=21439"},"modified":"2016-09-06T13:05:05","modified_gmt":"2016-09-06T16:05:05","slug":"sorpresa-de-play-off","status":"publish","type":"post","link":"http:\/\/labestiadeportiva.com\/lbd\/sorpresa-de-play-off\/","title":{"rendered":"Sorpresa de Play Off"},"content":{"rendered":"<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/09\/Imagen-3353.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-21440\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/09\/Imagen-3353-300x200.jpg\" alt=\"Imagen 3353\" width=\"300\" height=\"200\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/09\/Imagen-3353-300x200.jpg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/09\/Imagen-3353.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>El fin de semana comenzaron los Play Offs en la principal categor\u00eda de la Federaci\u00f3n Ushuaiense de f\u00fatbol de sal\u00f3n. Triunfos de Magallanes Azul, Argentinos del Sur, Comercio, Haf \u201cB\u201d y Los \u00d1ires. Se compite a mejor de tres partidos.<!--more--><\/p>\n<p>Finalmente el segmento mayor de primera divisi\u00f3n salonero de nuestra ciudad puso en marcha su etapa definitoria. Fueron cinco apasionantes encuentros jugados en el reducto policial del barrio 640 Viviendas.<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/09\/Imagen-3343.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-21441\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/09\/Imagen-3343-300x158.jpg\" alt=\"Imagen 3343\" width=\"300\" height=\"158\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/09\/Imagen-3343-300x158.jpg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/09\/Imagen-3343.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>La jornada dominguera se inici\u00f3 con Magallanes Azul quien se impuso claramente a Tigre por 11 a 0. Realidades diferentes para el primero y d\u00e9cimo clasificado a esta instancia.<\/p>\n<p>El multicampe\u00f3n en su recta final de preparaci\u00f3n rumbo a su segunda experiencia internacional: El Sudamericano de Clubes mientras que Tigre, de regreso de la Copa de Oro, se encuentra en la actualidad bastante lejos del nivel magall\u00e1nico.<\/p>\n<p>Dur\u00edsimo choque entre Ateneo Verde y HAF \u201cB\u201d. Partido con historia, re\u00f1ido que comenz\u00f3 con todo y termin\u00f3 favoreciendo a HAF \u201cB\u201d por 5 a 2. Niveles muy parejos que presagian una definici\u00f3n cerrada. A pesar de la victoria inicial para los de \u201cBeto\u201d Hern\u00e1ndez la serie est\u00e1 claramente abierta.<\/p>\n<p>La sorpresa lleg\u00f3 a media tarde. Todo parec\u00eda marchar sin inconvenientes para Magallanes Blanco quien se puso 3 a 0 y hasta llego a tener un parcial de 4 a 1 a favor pero se complic\u00f3.<\/p>\n<p>En un cierre para el infarto con m\u00e1s lucha que f\u00fatbol Argentinos consigui\u00f3 un enorme triunfo por 6 a 5 que lo motiva a seguir metiendo en una serie que en los papeles sab\u00eda era sumamente complicada.<\/p>\n<p>Al caer la noche se present\u00f3 el \u00faltimo campe\u00f3n Los \u00d1ires quien se midi\u00f3 ante Defensores Azul. Buena victoria para \u00d1ires quien dio el primer paso en su defensa del t\u00edtulo al imponerse por 7 a 3.<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/09\/Imagen-3345.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-21443\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/09\/Imagen-3345-300x201.jpg\" alt=\"Imagen 3345\" width=\"300\" height=\"201\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/09\/Imagen-3345-300x201.jpg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/09\/Imagen-3345.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Cerrando la fecha de la \u201cA\u201d Comercio gan\u00f3 con autoridad su primer partido de la serie a El Porvenir \u201cB\u201d por 6 a 2 dejando en claro su intensi\u00f3n de sumarse al lote de candidatos.<\/p>\n<p>Esto reci\u00e9n comienza. Los \u00d1ires el campe\u00f3n intentar\u00e1 repetir, Magallanes Azul dej\u00f3 en claro que intentar\u00e1 recuperar el 1 mantenido por m\u00e1s de una d\u00e9cada a pesar de tener como objetivo principal el repetir la buena imagen sudamericana.<\/p>\n<p><span style=\"color: #0000ff;\">Play Off 1\u00ba \u201cA\u201d<\/span><br \/>\nResultados (Juego 1)<br \/>\nMagallanes Azul 11 Tigre 0<br \/>\nMagallanes Blanco 5 Argentinos del Sur 6<br \/>\nComercio 6 El Porvenir \u201cB\u201d 2<br \/>\nAteneo Verde 2 HAF \u201cB\u201d 5<br \/>\nLos \u00d1ires 7 Defensores Azul 3<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/09\/Imagen-3355.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-21442\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/09\/Imagen-3355-300x174.jpg\" alt=\"Imagen 3355\" width=\"300\" height=\"174\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/09\/Imagen-3355-300x174.jpg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/09\/Imagen-3355.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 1.237<\/span><span class='epvc-label'> veces le\u00edda<\/span><\/div>\n<div class=\"jwsharethis\">\nShare this: \n<br \/>\n<a href=\"mailto:?subject=Sorpresa%20de%20Play%20Off&amp;body=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fsorpresa-de-play-off%2F\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/email.png\" alt=\"Share this page via Email\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.stumbleupon.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fsorpresa-de-play-off%2F&amp;title=Sorpresa+de+Play+Off\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/su.png\" alt=\"Share this page via Stumble Upon\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/digg.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fsorpresa-de-play-off%2F&amp;title=Sorpresa+de+Play+Off\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/digg.png\" alt=\"Share this page via Digg this\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.facebook.com\/sharer.php?u=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fsorpresa-de-play-off%2F&amp;t=Sorpresa+de+Play+Off\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/fb.png\" alt=\"Share this page via Facebook\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/twitter.com\/intent\/tweet?text=I+like+http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fsorpresa-de-play-off%2F&amp;title=Sorpresa+de+Play+Off\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/twitter.png\" alt=\"Share this page via Twitter\" \/>\n<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El fin de semana comenzaron los Play Offs en la principal categor\u00eda de la Federaci\u00f3n Ushuaiense de f\u00fatbol de sal\u00f3n. Triunfos de Magallanes Azul, Argentinos del Sur, Comercio, Haf \u201cB\u201d y Los \u00d1ires. Se compite a mejor de tres partidos. 1.237 veces le\u00edda Share this:<\/p>\n","protected":false},"author":1,"featured_media":21440,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,31,1],"tags":[2310,2468,215,117,83,987],"_links":{"self":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/21439"}],"collection":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/comments?post=21439"}],"version-history":[{"count":1,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/21439\/revisions"}],"predecessor-version":[{"id":21444,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/21439\/revisions\/21444"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media\/21440"}],"wp:attachment":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media?parent=21439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/categories?post=21439"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/tags?post=21439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}