{"id":29113,"date":"2018-08-14T11:55:25","date_gmt":"2018-08-14T14:55:25","guid":{"rendered":"http:\/\/labestiadeportiva.com\/lbd\/?p=29113"},"modified":"2018-08-14T13:23:48","modified_gmt":"2018-08-14T16:23:48","slug":"juntos-es-mejor","status":"publish","type":"post","link":"http:\/\/labestiadeportiva.com\/lbd\/juntos-es-mejor\/","title":{"rendered":"Juntos es mejor"},"content":{"rendered":"<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39072768_1966319646767894_2989323076539252736_n.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-29118\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39072768_1966319646767894_2989323076539252736_n-300x225.jpg\" alt=\"39072768_1966319646767894_2989323076539252736_n\" width=\"300\" height=\"225\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39072768_1966319646767894_2989323076539252736_n-300x225.jpg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39072768_1966319646767894_2989323076539252736_n.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>El pasado domingo en el Valle de Tierra Mayor el esqu\u00ed de fondo vivi\u00f3 su m\u00e1xima expresi\u00f3n. Por primera vez Marchablanca (32\u00b0 edici\u00f3n) y Ushuaia Loppet (8\u00b0 edici\u00f3n) se realizaron en forma simult\u00e1nea. Federico \u00abHormiga\u00bb Cichero consigui\u00f3 el quinto \u00e9xito en los 50 k donde la estonia Tiina Voogne gan\u00f3 entre las damas. Sobrino y t\u00eda, Mat\u00edas Zuloaga y Mar\u00eda Gir\u00f3 se impusieron en los 25 k. Poco m\u00e1s de 250 esquiadores formaron parte de los tres recorridos.<!--more--><\/p>\n<p>Finalmente y luego de algunos d\u00edas previos donde el clima complic\u00f3 las cosas, lluvia, viento y altas temperaturas, la jornada dominguera fue ideal vivida a pleno sol.<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/podio-ush-loppet.jpeg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-29115\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/podio-ush-loppet-300x200.jpeg\" alt=\"podio-ush-loppet\" width=\"300\" height=\"200\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/podio-ush-loppet-300x200.jpeg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/podio-ush-loppet-1024x682.jpeg 1024w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/podio-ush-loppet.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>La mayor\u00eda de los protagonistas entrevistados por LBD destacaron el buen estado del circuito, responsabilidad del Director de la Prueba el profesor Sebasti\u00e1n Menci.<\/p>\n<p>El tradicional campanazo lleg\u00f3 a las 10.45 donde un centenar de esquiadores comenzaron a desandar el valle por el circuito de la PIPEF.<\/p>\n<p>Cabe recordar que el recorrido promocional de 7.5 kil\u00f3metros se puso en marcha a partir de las 11.15 horas.<\/p>\n<p>Con los cr\u00e9ditos locales, \u00faltimos representantes ol\u00edmpicos, en cada categor\u00eda la posibilidad era clara y real para que la versi\u00f3n 2018 se quedara en Ushuaia.<\/p>\n<p>Mat\u00edas Zuloaga domin\u00f3 los 25 k seguido por Santos y Bianchi. El representante brasileno superar\u00eda al profesor local en los metros finales para asegurarse la segunda ubicaci\u00f3n. El vencedor marcar\u00eda en los relojes 1 hora 14 minutos y 25 segundos.<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39091774_1966319816767877_8520316071234764800_n.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-29119\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39091774_1966319816767877_8520316071234764800_n-300x158.jpg\" alt=\"39091774_1966319816767877_8520316071234764800_n\" width=\"300\" height=\"158\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39091774_1966319816767877_8520316071234764800_n-300x158.jpg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39091774_1966319816767877_8520316071234764800_n.jpg 889w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Entre las damas la experimentada Mar\u00eda Gir\u00f3 marcar\u00eda el camino. Una hora 42 minutos y 18 \u00a0segundos para ella. En breves declaraciones a LBD nos confes\u00f3 haber salido a entrenar por lo menos tres veces por semana y rindi\u00f3 sus frutos.<\/p>\n<p>Completaron el podio Andrea Bianchi a doce minutos de la ganadora mientras que el tercer escalon fue para la estadounidense Lebowitz.<\/p>\n<p>En cuanto a Ushuaia Loppet Federico Cichero fue implacable. Quinta edici\u00f3n ganada por el \u00abHormiga\u00bb, 2011, 2012, 2014, 2017 y 2018, en esta oportunidad con un registro de 2 horas y 42 minutos.<\/p>\n<p>Escoltas estonios, Kilsipuu y Torim, quienes completaron el trayecto veinte minutos despu\u00e9s que el ganador.<\/p>\n<p>Triunfadora estonia entre las damas, Tiina Voogne quien emple\u00f3 3 horas 52 minutos y 13 segundos para completar las dos vueltas de la prueba.<\/p>\n<p>Claudia Herlein est\u00e1 claramente de regreso, fue segunda a 7 minutos de la ganadora mientras que la h\u00fangara Vas complet\u00f3 el podio ingresando a la meta 15 minutos despu\u00e9s que la vencedora.<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39124603_1966319746767884_256074772050345984_n.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-29120\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39124603_1966319746767884_256074772050345984_n-300x225.jpg\" alt=\"39124603_1966319746767884_256074772050345984_n\" width=\"300\" height=\"225\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39124603_1966319746767884_256074772050345984_n-300x225.jpg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39124603_1966319746767884_256074772050345984_n.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>El deporte adaptado de Brasil en Tierra Mayor<\/p>\n<p>De la mano del referente Leandro Ribela un grupo de j\u00f3venes atletas adaptados realizaron diferentes pruebas. El cr\u00e9dito local Nicol\u00e1s Lima se sum\u00f3 a la propuesta. Desde LBD dialogamos brevemente con el brasile\u00f1o quien nos coment\u00f3 el proyecto de sumar deportistas con discapacidad a la pr\u00e1ctica invernal con miras a los pr\u00f3ximos paral\u00edmpicos de invierno.<\/p>\n<p>Buena y din\u00e1mica edici\u00f3n enfocada estrictamente en lo deportivo. El pr\u00f3ximo fin de semana el esqu\u00ed de fondo se disfrazar\u00e1 para darle lugar a la Mini Marchablanca donde los ni\u00f1os y atletas con discapacidad tendr\u00e1n su momento.<\/p>\n<p><span style=\"color: #0000ff;\"><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39203111_1966441403422385_7005842587563065344_n.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-29124\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39203111_1966441403422385_7005842587563065344_n-300x200.jpg\" alt=\"39203111_1966441403422385_7005842587563065344_n\" width=\"300\" height=\"200\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39203111_1966441403422385_7005842587563065344_n-300x200.jpg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39203111_1966441403422385_7005842587563065344_n.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Los podios por categor\u00edas<\/span><\/p>\n<p>Marchablanca 25 k (32\u00b0 edici\u00f3n)<\/p>\n<p>Caballeros<\/p>\n<p><span style=\"color: #ff0000;\">1\u00b0 Mat\u00edas Zuloaga 1h 14&#8242; 25\u00bb<\/span><\/p>\n<p>2\u00b0 V\u00edctor Santos (Brasil) 1h 19&#8242; 05\u00bb<\/p>\n<p>3\u00b0 Mart\u00edn Bianchi 1h 19&#8242; 09\u00bb<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39149914_1966319410101251_5572410957763706880_n.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-29121\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39149914_1966319410101251_5572410957763706880_n-300x225.jpg\" alt=\"39149914_1966319410101251_5572410957763706880_n\" width=\"300\" height=\"225\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39149914_1966319410101251_5572410957763706880_n-300x225.jpg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39149914_1966319410101251_5572410957763706880_n.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Damas<\/p>\n<p><span style=\"color: #ff0000;\">1\u00b0 Mar\u00eda Gir\u00f3 1h 42&#8242; 18&#8242;<\/span>&#8216;<\/p>\n<p>2\u00b0 Andrea Bianchi 1h 54&#8242; 07\u00bb<\/p>\n<p>3\u00b0 Gretchen Lebowitz (EE.UU) 2h 22&#8217; 57\u00bb<\/p>\n<p>Ushuaia Loppet 50 k (8\u00b0 Edici\u00f3n)<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39162739_1966441326755726_8367578852276305920_n.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-29125\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39162739_1966441326755726_8367578852276305920_n-300x200.jpg\" alt=\"39162739_1966441326755726_8367578852276305920_n\" width=\"300\" height=\"200\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39162739_1966441326755726_8367578852276305920_n-300x200.jpg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39162739_1966441326755726_8367578852276305920_n.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Caballeros<\/p>\n<p><span style=\"color: #ff0000;\">1\u00b0 Federico \u00abHormiga\u00bb Cichero 2h 42&#8217;00\u00bb<\/span><\/p>\n<p>2\u00b0 Avo Kilsipuu (Estonia) 3h 07&#8242; 55\u00bb<\/p>\n<p>3\u00b0 Madis Torim (Estonia) 3h 10&#8242; 56\u00bb<\/p>\n<p>Damas<\/p>\n<p><span style=\"color: #ff0000;\">1\u00b0 Tiina Voogne (Estonia) 3h 52&#8242; 13\u00bb<\/span><\/p>\n<p>2\u00b0 Claudia Herlein 3h 59&#8242; 04\u00bb<\/p>\n<p>3\u00b0 Erika Vas (Hungr\u00eda) 4h 07&#8242; 05\u00bb<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39229095_1966319480101244_7407860344036524032_n.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-29122\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39229095_1966319480101244_7407860344036524032_n-169x300.jpg\" alt=\"39229095_1966319480101244_7407860344036524032_n\" width=\"169\" height=\"300\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39229095_1966319480101244_7407860344036524032_n-169x300.jpg 169w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/08\/39229095_1966319480101244_7407860344036524032_n.jpg 540w\" sizes=\"(max-width: 169px) 100vw, 169px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 1.402<\/span><span class='epvc-label'> veces le\u00edda<\/span><\/div>\n<div class=\"jwsharethis\">\nShare this: \n<br \/>\n<a href=\"mailto:?subject=Juntos%20es%20mejor&amp;body=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fjuntos-es-mejor%2F\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/email.png\" alt=\"Share this page via Email\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.stumbleupon.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fjuntos-es-mejor%2F&amp;title=Juntos+es+mejor\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/su.png\" alt=\"Share this page via Stumble Upon\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/digg.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fjuntos-es-mejor%2F&amp;title=Juntos+es+mejor\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/digg.png\" alt=\"Share this page via Digg this\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.facebook.com\/sharer.php?u=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fjuntos-es-mejor%2F&amp;t=Juntos+es+mejor\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/fb.png\" alt=\"Share this page via Facebook\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/twitter.com\/intent\/tweet?text=I+like+http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fjuntos-es-mejor%2F&amp;title=Juntos+es+mejor\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/twitter.png\" alt=\"Share this page via Twitter\" \/>\n<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El pasado domingo en el Valle de Tierra Mayor el esqu\u00ed de fondo vivi\u00f3 su m\u00e1xima expresi\u00f3n. Por primera vez Marchablanca (32\u00b0 edici\u00f3n) y Ushuaia Loppet (8\u00b0 edici\u00f3n) se realizaron en forma simult\u00e1nea. Federico \u00abHormiga\u00bb Cichero consigui\u00f3 el quinto \u00e9xito en los 50 k donde la estonia Tiina Voogne gan\u00f3 entre las damas. Sobrino y &hellip; <a href=\"http:\/\/labestiadeportiva.com\/lbd\/juntos-es-mejor\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Juntos es mejor<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":29118,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,4,6,41,29,1],"tags":[893,42,4832,828,3660],"_links":{"self":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/29113"}],"collection":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/comments?post=29113"}],"version-history":[{"count":4,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/29113\/revisions"}],"predecessor-version":[{"id":29126,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/29113\/revisions\/29126"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media\/29118"}],"wp:attachment":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media?parent=29113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/categories?post=29113"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/tags?post=29113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}