{"id":32985,"date":"2019-08-09T21:37:11","date_gmt":"2019-08-10T00:37:11","guid":{"rendered":"http:\/\/labestiadeportiva.com\/lbd\/?p=32985"},"modified":"2019-08-09T21:37:11","modified_gmt":"2019-08-10T00:37:11","slug":"agenda-reducida-2","status":"publish","type":"post","link":"http:\/\/labestiadeportiva.com\/lbd\/agenda-reducida-2\/","title":{"rendered":"Agenda Reducida"},"content":{"rendered":"<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/Screenshot_20190809-2125172.png\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-32986\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/Screenshot_20190809-2125172-300x198.png\" alt=\"Screenshot_20190809-212517~2\" width=\"300\" height=\"198\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/Screenshot_20190809-2125172-300x198.png 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/Screenshot_20190809-2125172-1024x674.png 1024w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/Screenshot_20190809-2125172.png 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Tan solo 48 horas, viernes y s\u00e1bado para la pr\u00e1ctica del deporte. El domingo ser\u00e1 el momento de las PASO. Ver\u00e1n acci\u00f3n futsal AFA, b\u00e1squet, esqu\u00ed de fondo, Futsal federado y hockey pista. Asimismo este viernes, en el taller de Ivandic, t\u00e9cnica y administrativa para los ushuaienses que estar\u00e1n presentes en la 46\u00b0 edici\u00f3n del Gran Premio de la Hermandad. Desde LBD, los detalles.<!--more--><\/p>\n<p>Futsal AFA<\/p>\n<p>Viernes de fase clasificatoria de la Liga Nacional del Consejo Federal. Desde las 22 horas chocar\u00e1n Centro Galicia y Arturo Prat.<\/p>\n<p>Asimismo el s\u00e1bado desde las 12.30, en el mismo escenario se jugar\u00e1n las revanchas de la Copa Ushuaia 4\u00b0 edici\u00f3n.<\/p>\n<p>Ser\u00e1n siete partidos culminando alrededor de las 23 horas. No fue programado Camioneros\/Arturo Prat por la suspensi\u00f3n del primer encuentro que se encuentra a resoluci\u00f3n del Tribunal de Disciplina.<\/p>\n<p>B\u00e1squet<\/p>\n<p>Desde la Federaci\u00f3n se programaron 10 juegos en ambas ciudades. Un duelo este viernes a las 21.45 en mayores masculino entre Defensores y Universitario \u00abRojo\u00bb para continuar al s\u00e1bado en el gimnasio de la Escuela N\u00b0 7, de 9.30 a 18, con partidos U13 y U15.<\/p>\n<p>En la capital provincial, siempre el s\u00e1bado, la Cancha 4 recibir\u00e1 tres encuentros de 11 a 16.30 el \u00faltimo de primera masculino entre Colegio del Sur y Metal\u00fargico.<\/p>\n<p>Esqu\u00ed de Fondo<\/p>\n<p>Una semana despu\u00e9s, los organizadores postergaron por cuestiones clim\u00e1ticas, y con cambio de escenario inclu\u00eddo, la competencia se trasladar\u00e1 de la pista \u00abFrancisco Jerman\u00bb a la \u00abGustavo Gir\u00f3\u00bb de Tierra Mayor, se disputar\u00e1 este s\u00e1bado la 2\u00b0 fecha del Campeonato Fueguino.<\/p>\n<p>Con el formato de Sprint XC Cross claramente orientado al semillero del fondo, donde actuar\u00e1n los segmentos Piojos, Infantiles I y II y Cadetes I y II. Concentraci\u00f3n desde las 10.45 para 11.30 entrar en competencia.<\/p>\n<p>Futsal Federado<\/p>\n<p>La Federaci\u00f3n Ushuaiense centrar\u00e1 casi todas sus acciones el s\u00e1bado, los infantiles es dos escenarios: gimnasios del Colegio Sobral y \u00abMirador de Los Andes (640 Viviendas).<\/p>\n<p>En las superiores los \u00abviejitos\u00bb entrar\u00e1n en escena. Ser\u00e1 en Campolter de 15 a 21 horas con partidos de Senior y Veteranos. Dos encuentros el domingo despu\u00e9s de la veda. En el mismo escenario de 21 a 23.30 para C15 y primera.<\/p>\n<p>Asimismo en R\u00edo Grande el viernes y s\u00e1bado se repetir\u00e1n los choques de las selecciones C20 que se prepar\u00e1n para su incursi\u00f3n nacional.<\/p>\n<p>Hockey Pista<\/p>\n<p>Fecha reducida, n\u00famero 12, de la Liga Provincial. Tan solo tres partidos el s\u00e1bado en el gimnasio del URC, de 17 a 20 para los segmentos Sub 14 y Sub 16 damas.<\/p>\n<p>Automovilismo<\/p>\n<p>Viernes de Verificaci\u00f3n T\u00e9cnica y Administrativa para los binomios ushuaienses que estar\u00e1n presente en la 46\u00b0 edici\u00f3n del GPH. Se efectuar\u00e1 de 10 a 16 horas en el taller de la familia Ivanfic, ubicado en el sector de la \u00abTata\u00bb Duque. Los objetos repetir\u00e1n la experiencia el lunes en R\u00edo Grande de 9 a 14 horas.<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/Screenshot_20190809-1116442.png\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-32987\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/Screenshot_20190809-1116442-257x300.png\" alt=\"Screenshot_20190809-111644~2\" width=\"257\" height=\"300\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/Screenshot_20190809-1116442-257x300.png 257w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/Screenshot_20190809-1116442-876x1024.png 876w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/Screenshot_20190809-1116442.png 1080w\" sizes=\"(max-width: 257px) 100vw, 257px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/IMG-20190808-WA0036.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-32988\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/IMG-20190808-WA0036-169x300.jpg\" alt=\"IMG-20190808-WA0036\" width=\"169\" height=\"300\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/IMG-20190808-WA0036-169x300.jpg 169w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/IMG-20190808-WA0036-576x1024.jpg 576w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/IMG-20190808-WA0036.jpg 720w\" sizes=\"(max-width: 169px) 100vw, 169px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/FB_IMG_1565355544314.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-32989\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/FB_IMG_1565355544314-226x300.jpg\" alt=\"FB_IMG_1565355544314\" width=\"226\" height=\"300\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/FB_IMG_1565355544314-226x300.jpg 226w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/FB_IMG_1565355544314.jpg 724w\" sizes=\"(max-width: 226px) 100vw, 226px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/FB_IMG_1565355584139.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-32990\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/FB_IMG_1565355584139-268x300.jpg\" alt=\"FB_IMG_1565355584139\" width=\"268\" height=\"300\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/FB_IMG_1565355584139-268x300.jpg 268w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/FB_IMG_1565355584139.jpg 673w\" sizes=\"(max-width: 268px) 100vw, 268px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/IMG-20190809-WA00012.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-32991\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/IMG-20190809-WA00012-300x125.jpg\" alt=\"IMG-20190809-WA0001~2\" width=\"300\" height=\"125\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/IMG-20190809-WA00012-300x125.jpg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/IMG-20190809-WA00012.jpg 1013w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/IMG-20190809-WA00002.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-32992\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/IMG-20190809-WA00002-300x70.jpg\" alt=\"IMG-20190809-WA0000~2\" width=\"300\" height=\"70\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/IMG-20190809-WA00002-300x70.jpg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/IMG-20190809-WA00002.jpg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/IMG-20190809-WA00003.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-32993\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/IMG-20190809-WA00003-300x86.jpg\" alt=\"IMG-20190809-WA0000~3\" width=\"300\" height=\"86\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/IMG-20190809-WA00003-300x86.jpg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2019\/08\/IMG-20190809-WA00003.jpg 720w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 1.053<\/span><span class='epvc-label'> veces le\u00edda<\/span><\/div>\n<div class=\"jwsharethis\">\nShare this: \n<br \/>\n<a href=\"mailto:?subject=Agenda%20Reducida&amp;body=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fagenda-reducida-2%2F\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/email.png\" alt=\"Share this page via Email\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.stumbleupon.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fagenda-reducida-2%2F&amp;title=Agenda+Reducida\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/su.png\" alt=\"Share this page via Stumble Upon\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/digg.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fagenda-reducida-2%2F&amp;title=Agenda+Reducida\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/digg.png\" alt=\"Share this page via Digg this\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.facebook.com\/sharer.php?u=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fagenda-reducida-2%2F&amp;t=Agenda+Reducida\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/fb.png\" alt=\"Share this page via Facebook\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/twitter.com\/intent\/tweet?text=I+like+http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fagenda-reducida-2%2F&amp;title=Agenda+Reducida\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/twitter.png\" alt=\"Share this page via Twitter\" \/>\n<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tan solo 48 horas, viernes y s\u00e1bado para la pr\u00e1ctica del deporte. El domingo ser\u00e1 el momento de las PASO. Ver\u00e1n acci\u00f3n futsal AFA, b\u00e1squet, esqu\u00ed de fondo, Futsal federado y hockey pista. Asimismo este viernes, en el taller de Ivandic, t\u00e9cnica y administrativa para los ushuaienses que estar\u00e1n presentes en la 46\u00b0 edici\u00f3n del &hellip; <a href=\"http:\/\/labestiadeportiva.com\/lbd\/agenda-reducida-2\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Agenda Reducida<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":32986,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,1],"tags":[62,3660],"_links":{"self":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/32985"}],"collection":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/comments?post=32985"}],"version-history":[{"count":1,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/32985\/revisions"}],"predecessor-version":[{"id":32994,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/32985\/revisions\/32994"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media\/32986"}],"wp:attachment":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media?parent=32985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/categories?post=32985"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/tags?post=32985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}