{"id":39814,"date":"2021-09-21T13:12:39","date_gmt":"2021-09-21T16:12:39","guid":{"rendered":"http:\/\/labestiadeportiva.com\/lbd\/?p=39814"},"modified":"2021-09-21T13:12:39","modified_gmt":"2021-09-21T16:12:39","slug":"mundial-con-presencia-fueguina","status":"publish","type":"post","link":"http:\/\/labestiadeportiva.com\/lbd\/mundial-con-presencia-fueguina\/","title":{"rendered":"Mundial con presencia fueguina"},"content":{"rendered":"<p>Por Marcelo Zayas (Colaboraci\u00f3n Especial para LBD)<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2021\/09\/IMG-20210921-WA0049.jpg\"><img loading=\"lazy\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2021\/09\/IMG-20210921-WA0049.jpg\" alt=\"IMG-20210921-WA0049\" width=\"1156\" height=\"769\" class=\"aligncenter size-full wp-image-39815\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2021\/09\/IMG-20210921-WA0049.jpg 1156w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2021\/09\/IMG-20210921-WA0049-300x200.jpg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2021\/09\/IMG-20210921-WA0049-1024x681.jpg 1024w\" sizes=\"(max-width: 1156px) 100vw, 1156px\" \/><\/a><br \/>\nDesde el 8 al 19 de septiembre del corriente a\u00f1o se llev\u00f3 a cabo el Mundial de Roller Hockey de Damas y Caballeros, organizados por la World Skate. Dichos torneos se realizaron en la ciudad de Roccaraso, Italia, con la participaci\u00f3n de la Selecci\u00f3n Argentina dirigida por Gustavo R\u00edos y Julio Mercere, de la misma formaron parte los fueguinos Lucila Soto y Adriano Mazzaferro surgidos del club Dragones de la ciudad de R\u00edo Grande.<!--more--><\/p>\n<p>En primera instancia se llev\u00f3 a cabo el torneo de Damas. El equipo argentino form\u00f3 parte del Grupo B, junto con Suiza, Italia, Espa\u00f1a y Colombia. Las argentinas debutaron en el torneo ganando 6-1 a Suiza siendo la fueguina Lucila Soto qui\u00e9n abri\u00f3 el tanteador del partido, marcando el primer gol argentino, posteriormente se enfrentaron a Italia, siendo derrotadas en Over Time 1-0, ante Espa\u00f1a cayeron por 5-0 mientras Colombia las super\u00f3 por un apretado 2-1. <\/p>\n<p>Con estos resultados pasaron a Cuartos de Final, el rival fue Francia cayendo por 3-1. Para definir su ubicaci\u00f3n del 5\u00b0 al 8\u00b0 puesto del torneo, se enfrentaron a Letonia, ganando por 2-1 obteniendo el 5\u00b0 puesto, al derrotar a Italia por 3-0, siendo este el mejor puesto hasta ahora obtenido por las damas.<\/p>\n<p>El seleccionado masculino forma parte del Pool \u00abB\u00bb de la World Skate, segunda categor\u00eda. Argentina form\u00f3 parte del grupo \u00abD\u00bb junto a Alemania, Namibia e India, en el primer partido derrot\u00f3 a Alemania por 3-0, en el segundo cay\u00f3 ante Namibia 1-0 y venci\u00f3 le a India 15-0. <\/p>\n<p>Ya en Cuartos de Final le gan\u00f3 a Polonia 6-2, en semifinales triunf\u00f3 ante Letonia por 3-1 mientras que en la final se volvi\u00f3 a enfrentar a Namibia derrot\u00e1ndolo en Over Time 2-1. <\/p>\n<p>Argentina y Namibia se ganaron el derecho a pelear un puesto en el Pool A, para esto deber\u00e1n enfrentar en el pr\u00f3ximo mundial a los dos \u00faltimos clasificados del Pool A, de ganar pasar\u00eda a formar parte de dicha categor\u00eda.<\/p>\n<p>Para poder participar de este mundial, que deb\u00eda realizarse en Colombia en 2020, y fue reprogramado por la pandemia, los jugadores continuaron con las concentraciones v\u00eda zoom y posteriormente se realizaron concentraciones regionales, en la medida que se levantaron las restricciones.<\/p>\n<p>Cabe agregar que de la etapa preselectiva tambi\u00e9n fueron convocados los fueguinos Gaspar L\u00f3pez Silva y Maitena Zayas Diaz, provenientes del Club Andino Ushuaia y en la categor\u00eda Junior, Danilo Lambert, Luisina Harvertz, Juan Canalis, Ivo Lambert, Guillermo Andrade, Emiliano Meretta, Ivo Carmona, Alvaro Carmona, Jose Chevallier del club Dragones quienes contin\u00faan participando de las concentraciones  con miras al Mundial Junior y al Sudamericano a realizarse en la ciudad de San Juan en febrero\/2022.<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2021\/09\/IMG-20210921-WA0048.jpg\"><img loading=\"lazy\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2021\/09\/IMG-20210921-WA0048.jpg\" alt=\"IMG-20210921-WA0048\" width=\"768\" height=\"510\" class=\"aligncenter size-full wp-image-39816\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2021\/09\/IMG-20210921-WA0048.jpg 768w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2021\/09\/IMG-20210921-WA0048-300x199.jpg 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><\/p>\n<p>Los partidos fueron transmitidos en vivo por internet en el canal de la World Skate www.worldskate.tv . Sitio oficial www.worldskate.org.<\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 1.244<\/span><span class='epvc-label'> veces le\u00edda<\/span><\/div>\n<div class=\"jwsharethis\">\nShare this: \n<br \/>\n<a href=\"mailto:?subject=Mundial%20con%20presencia%20fueguina&amp;body=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fmundial-con-presencia-fueguina%2F\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/email.png\" alt=\"Share this page via Email\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.stumbleupon.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fmundial-con-presencia-fueguina%2F&amp;title=Mundial+con+presencia+fueguina\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/su.png\" alt=\"Share this page via Stumble Upon\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/digg.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fmundial-con-presencia-fueguina%2F&amp;title=Mundial+con+presencia+fueguina\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/digg.png\" alt=\"Share this page via Digg this\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.facebook.com\/sharer.php?u=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fmundial-con-presencia-fueguina%2F&amp;t=Mundial+con+presencia+fueguina\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/fb.png\" alt=\"Share this page via Facebook\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/twitter.com\/intent\/tweet?text=I+like+http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fmundial-con-presencia-fueguina%2F&amp;title=Mundial+con+presencia+fueguina\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/twitter.png\" alt=\"Share this page via Twitter\" \/>\n<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por Marcelo Zayas (Colaboraci\u00f3n Especial para LBD) Desde el 8 al 19 de septiembre del corriente a\u00f1o se llev\u00f3 a cabo el Mundial de Roller Hockey de Damas y Caballeros, organizados por la World Skate. Dichos torneos se realizaron en la ciudad de Roccaraso, Italia, con la participaci\u00f3n de la Selecci\u00f3n Argentina dirigida por Gustavo &hellip; <a href=\"http:\/\/labestiadeportiva.com\/lbd\/mundial-con-presencia-fueguina\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Mundial con presencia fueguina<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":39815,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,4,6,1,4608],"tags":[211,3660,4609],"_links":{"self":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/39814"}],"collection":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/comments?post=39814"}],"version-history":[{"count":1,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/39814\/revisions"}],"predecessor-version":[{"id":39817,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/39814\/revisions\/39817"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media\/39815"}],"wp:attachment":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media?parent=39814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/categories?post=39814"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/tags?post=39814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}