{"id":3994,"date":"2013-04-19T16:06:47","date_gmt":"2013-04-19T16:06:47","guid":{"rendered":"http:\/\/labestiadeportiva.com\/lbd\/?p=3994"},"modified":"2013-04-19T16:08:19","modified_gmt":"2013-04-19T16:08:19","slug":"todos-por-una-misma-ilusion","status":"publish","type":"post","link":"http:\/\/labestiadeportiva.com\/lbd\/todos-por-una-misma-ilusion\/","title":{"rendered":"Todos por una misma ilusi\u00f3n"},"content":{"rendered":"<p><em>Por Mauricio Zentner Lavori (Corresponsal LBD en Buenos Aires)<\/em><\/p>\n<p>La Copa Bridgestone Libertadores ha llegado al final de la fase de grupos y ya defini\u00f3 las ubicaciones de los 16 clasificados para los cruces de Octavos. Boca, Newell\u00b4s, V\u00e9lez y Tigre son los argentinos que siguen en carrera, pero uno de ellos necesariamente quedar\u00e1 afuera. El an\u00e1lisis en LBD.<\/p>\n<p style=\"text-align: left;\"><span style=\"font-size: 13px;\"><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/04\/MZL4.jpg\"><img loading=\"lazy\" class=\"aligncenter  wp-image-3995\" title=\"MZL\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/04\/MZL4.jpg\" alt=\"\" width=\"540\" height=\"210\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/04\/MZL4.jpg 900w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/04\/MZL4-300x116.jpg 300w\" sizes=\"(max-width: 540px) 100vw, 540px\" \/><\/a><!--moreLeer nota completa --><br \/>\nTodos buscan el t\u00edtulo.\u00a0Todos quieren levantar la copa. Todos salen a comerse la cancha y a dejar todo por un mismo objetivo.<\/span><\/p>\n<p>La Copa Libertadores es deseo de todo aquel que se encuentre con una pelota de f\u00fatbol y ayer, cuando se terminaba de definir el Grupo 8, todos estaban atentos al fixture, para saber que cruce tocar\u00eda en Octavos de Final.<\/p>\n<p>Finalmente, con la igualdad de Huachipato ante Gremio y el triunfo de Fluminense ante Caracas, las series han dejado como dato resonante que la final de 2012 entre Boca y Corinthians tendr\u00e1 segundo cap\u00edtulo, poniendo al conjunto de Bianchi ante un equipo al que muchos dan el mote de candidato.<\/p>\n<p>Y adem\u00e1s hay un dato anecd\u00f3tico. Como el 5 de Mayo se juega el Supercl\u00e1sico por el certamen local, puede ser que el \u201cVirrey\u201d elija suplentes teniendo en cuenta que el 8 disputar\u00eda la revancha ante el Timao.<\/p>\n<p>Por otro lado tendremos un choque cien por ciento argentino entre V\u00e9lez y Newell\u00b4s, obligando a dirimir un boleto a Cuartos mano a mano. Los de Gareca parecen m\u00e1s confiados y s\u00f3lidos, pero Scocco y compa\u00f1\u00eda quieren dar un golpe continental.<\/p>\n<p>En tanto el Matador de Victoria, Tigre, cerr\u00f3 una proeza hist\u00f3rica tras superar 5-3 a Libertad como visitante meti\u00e9ndose por primera vez en Octavos de la Libertadores y aspirando a llegar lo m\u00e1s lejos posible con figuras como Mat\u00edas P\u00e9rez Garc\u00eda o Rub\u00e9n Botta que vienen dando que hablar con sus actuaciones. Olimpia, otro club paraguayo, ser\u00e1 el obst\u00e1culo a superar.<\/p>\n<p>Analizando las otras llaves, se puede destacar Atl\u00e9tico Mineiro vs. San Pablo y la enorme cantidad de equipos brasileros en competencia. Son seis, logrando un hito que ning\u00fan pa\u00eds hab\u00eda conseguido hasta el momento. Ahora depender\u00e1 de los resultados cu\u00e1n lejos llegue cada uno.<\/p>\n<p>La semana que viene ya se pone en marcha y s\u00f3lo detendr\u00e1 su recorrido luego de los cuartos por la Copa Confederaciones Brasil 2013. Las semifinales y finales se llevar\u00e1n a cabo en el mes de Julio.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/04\/MZL-25.jpg\"><img loading=\"lazy\" class=\"aligncenter  wp-image-3996\" title=\"MZL 2\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/04\/MZL-25.jpg\" alt=\"\" width=\"577\" height=\"542\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/04\/MZL-25.jpg 961w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/04\/MZL-25-300x282.jpg 300w\" sizes=\"(max-width: 577px) 100vw, 577px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 1.451<\/span><span class='epvc-label'> veces le\u00edda<\/span><\/div>\n<div class=\"jwsharethis\">\nShare this: \n<br \/>\n<a href=\"mailto:?subject=Todos%20por%20una%20misma%20ilusi%C3%B3n&amp;body=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Ftodos-por-una-misma-ilusion%2F\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/email.png\" alt=\"Share this page via Email\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.stumbleupon.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Ftodos-por-una-misma-ilusion%2F&amp;title=Todos+por+una+misma+ilusi%C3%B3n\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/su.png\" alt=\"Share this page via Stumble Upon\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/digg.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Ftodos-por-una-misma-ilusion%2F&amp;title=Todos+por+una+misma+ilusi%C3%B3n\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/digg.png\" alt=\"Share this page via Digg this\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.facebook.com\/sharer.php?u=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Ftodos-por-una-misma-ilusion%2F&amp;t=Todos+por+una+misma+ilusi%C3%B3n\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/fb.png\" alt=\"Share this page via Facebook\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/twitter.com\/intent\/tweet?text=I+like+http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Ftodos-por-una-misma-ilusion%2F&amp;title=Todos+por+una+misma+ilusi%C3%B3n\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/twitter.png\" alt=\"Share this page via Twitter\" \/>\n<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por Mauricio Zentner Lavori (Corresponsal LBD en Buenos Aires) La Copa Bridgestone Libertadores ha llegado al final de la fase de grupos y ya defini\u00f3 las ubicaciones de los 16 clasificados para los cruces de Octavos. Boca, Newell\u00b4s, V\u00e9lez y Tigre son los argentinos que siguen en carrera, pero uno de ellos necesariamente quedar\u00e1 afuera. &hellip; <a href=\"http:\/\/labestiadeportiva.com\/lbd\/todos-por-una-misma-ilusion\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Todos por una misma ilusi\u00f3n<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":3995,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,6,1],"tags":[245,465,570,481,569,200,480],"_links":{"self":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/3994"}],"collection":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/comments?post=3994"}],"version-history":[{"count":2,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/3994\/revisions"}],"predecessor-version":[{"id":3998,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/3994\/revisions\/3998"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media\/3995"}],"wp:attachment":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media?parent=3994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/categories?post=3994"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/tags?post=3994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}