{"id":41466,"date":"2022-03-28T20:07:59","date_gmt":"2022-03-28T23:07:59","guid":{"rendered":"http:\/\/labestiadeportiva.com\/lbd\/?p=41466"},"modified":"2022-03-28T20:10:21","modified_gmt":"2022-03-28T23:10:21","slug":"el-fenomeno-sin-precedentes","status":"publish","type":"post","link":"http:\/\/labestiadeportiva.com\/lbd\/el-fenomeno-sin-precedentes\/","title":{"rendered":"El fen\u00f3meno sin precedentes"},"content":{"rendered":"<p>Por Javier Nicol\u00e1s Baroli (Corresponsal LBD en R\u00edo Gallegos)<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2022\/03\/messilljpeg.jpeg\"><img loading=\"lazy\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2022\/03\/messilljpeg-300x169.jpeg\" alt=\"messilljpeg\" width=\"300\" height=\"169\" class=\"aligncenter size-medium wp-image-41468\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2022\/03\/messilljpeg-300x169.jpeg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2022\/03\/messilljpeg-640x360.jpeg 640w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2022\/03\/messilljpeg.jpeg 642w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><br \/>\nLa era Scaloni y Messi sigue dando que hablar. La revoluci\u00f3n de una Selecci\u00f3n que, con una mochila cargada de ilusiones, sigue enamorando en cada presentaci\u00f3n, ya piensa en Qatar 2022. Las claves de un verdadero fen\u00f3meno futbol\u00edstico.<!--more--><\/p>\n<p>\u201cPap\u00e1, hoy juega Argentina\u201d me recuerda mi hijo de apenas 7 a\u00f1os al despertarse. Impensado unos a\u00f1os atr\u00e1s. Tal vez la frase era la misma, pero la impronta hubiera sido otra, de desaz\u00f3n, desesperanza, aplomo y hasta de desilusi\u00f3n. <\/p>\n<p>Hoy tachamos los d\u00edas en el calendario que est\u00e1 pegado a la heladera, las entradas vuelan en apenas minutos. Cuesta encontrar fen\u00f3menos mundiales en torno a una selecci\u00f3n, Argentina una vez m\u00e1s, es ese motivo de an\u00e1lisis cient\u00edfico que cuesta analizar y entender.<\/p>\n<p>La mudanza a la \u00abBombonera\u00bb era toda una incertidumbre. Primero por saber en qu\u00e9 condiciones se encontraba el estadio, pero tambi\u00e9n por ser un reducto que cuesta ser relacionado a la albiceleste. <\/p>\n<p>Rompiendo toda regla y hasta desafiando, una vez, a la ciencia, Scaloni, Messi y compa\u00f1\u00eda fueron a la Boca y fue una fiesta, pocas veces antes vista. <\/p>\n<p>Cuando digo que \u00e9sta selecci\u00f3n rompe cualquier molde o situaci\u00f3n que pueda ser analizada, es realmente real. Y eso tambi\u00e9n ilusiona.<\/p>\n<p>La eliminatoria para Argentina se cerrar\u00e1 este martes 20.30 horas cuando visite a Ecuador, en lo que tambi\u00e9n ser\u00e1 una fiesta ya que la selecci\u00f3n que dirige Gustavo Alfaro consigui\u00f3 pasaporte directo a Qatar la semana pasada. <\/p>\n<p>Argentina ostenta un record incre\u00edble de 30 partidos. Es conveniente llegar a Qatar con esa condici\u00f3n? Para quien suscribe la presente, no. <\/p>\n<p>Se viene el roce Europeo, algo necesario para tomar real dimensi\u00f3n de nuestro potencial. <\/p>\n<p>El 1\u00b0 de Junio en Wembley, Argentina enfrentar\u00e1 a la recientemente eliminada Italia. Todo examen es necesario y oportuno para seguir acrecentando la ilusi\u00f3n y consolidar una idea futbol\u00edstica revolucionaria desde la teor\u00eda a la practica.<\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 1.241<\/span><span class='epvc-label'> veces le\u00edda<\/span><\/div>\n<div class=\"jwsharethis\">\nShare this: \n<br \/>\n<a href=\"mailto:?subject=El%20fen%C3%B3meno%20sin%20precedentes&amp;body=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fel-fenomeno-sin-precedentes%2F\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/email.png\" alt=\"Share this page via Email\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.stumbleupon.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fel-fenomeno-sin-precedentes%2F&amp;title=El+fen%C3%B3meno+sin+precedentes\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/su.png\" alt=\"Share this page via Stumble Upon\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/digg.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fel-fenomeno-sin-precedentes%2F&amp;title=El+fen%C3%B3meno+sin+precedentes\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/digg.png\" alt=\"Share this page via Digg this\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.facebook.com\/sharer.php?u=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fel-fenomeno-sin-precedentes%2F&amp;t=El+fen%C3%B3meno+sin+precedentes\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/fb.png\" alt=\"Share this page via Facebook\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/twitter.com\/intent\/tweet?text=I+like+http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fel-fenomeno-sin-precedentes%2F&amp;title=El+fen%C3%B3meno+sin+precedentes\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/twitter.png\" alt=\"Share this page via Twitter\" \/>\n<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por Javier Nicol\u00e1s Baroli (Corresponsal LBD en R\u00edo Gallegos) La era Scaloni y Messi sigue dando que hablar. La revoluci\u00f3n de una Selecci\u00f3n que, con una mochila cargada de ilusiones, sigue enamorando en cada presentaci\u00f3n, ya piensa en Qatar 2022. Las claves de un verdadero fen\u00f3meno futbol\u00edstico. 1.241 veces le\u00edda Share this:<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,57,14,1],"tags":[4715,4830,88],"_links":{"self":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/41466"}],"collection":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/comments?post=41466"}],"version-history":[{"count":2,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/41466\/revisions"}],"predecessor-version":[{"id":41469,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/41466\/revisions\/41469"}],"wp:attachment":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media?parent=41466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/categories?post=41466"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/tags?post=41466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}