{"id":48011,"date":"2023-12-01T00:43:20","date_gmt":"2023-12-01T03:43:20","guid":{"rendered":"http:\/\/labestiadeportiva.com\/lbd\/?p=48011"},"modified":"2023-12-01T00:48:58","modified_gmt":"2023-12-01T03:48:58","slug":"despedida-con-medallas-para-la-natacion-y-el-atletismo","status":"publish","type":"post","link":"http:\/\/labestiadeportiva.com\/lbd\/despedida-con-medallas-para-la-natacion-y-el-atletismo\/","title":{"rendered":"Despedida con medallas para la nataci\u00f3n y el atletismo"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2023\/11\/FB_IMG_1701388737310.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"883\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2023\/11\/FB_IMG_1701388737310-1024x883.jpg\" alt=\"\" class=\"wp-image-48012\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2023\/11\/FB_IMG_1701388737310-1024x883.jpg 1024w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2023\/11\/FB_IMG_1701388737310-300x259.jpg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2023\/11\/FB_IMG_1701388737310-768x662.jpg 768w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2023\/11\/FB_IMG_1701388737310-640x552.jpg 640w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2023\/11\/FB_IMG_1701388737310.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2022\/11\/CARA_PEREZ-2.jpg\"><img loading=\"lazy\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2022\/11\/CARA_PEREZ-2.jpg\" alt=\"\" class=\"wp-image-43576\" width=\"360\" height=\"73\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2022\/11\/CARA_PEREZ-2.jpg 600w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2022\/11\/CARA_PEREZ-2-300x62.jpg 300w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/a><\/figure>\n\n\n\n<p>Se viven los instantes finales en los Juegos EPADE de la provincia de La Pampa. Milagros Ver\u00f3n Witte fue segunda en la prueba de 50 metros pecho sumando la segunda medalla de la disciplina. <\/p>\n\n\n\n<p>El atletismo concluy\u00f3 con las medallas de \u00abAnto\u00bb Ojeda y Josefina Garc\u00eda. El judo en el cierre compite por equipos mientras que los deportes de conjunto concluyeron su participaci\u00f3n. Las fotos son gentileza de Prensa Secretaria de Deportes Provincial.<\/p>\n\n\n\n<!--more-->\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2023\/11\/FB_IMG_1701398601483.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"682\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2023\/11\/FB_IMG_1701398601483-1024x682.jpg\" alt=\"\" class=\"wp-image-48013\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2023\/11\/FB_IMG_1701398601483-1024x682.jpg 1024w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2023\/11\/FB_IMG_1701398601483-300x200.jpg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2023\/11\/FB_IMG_1701398601483-768x511.jpg 768w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2023\/11\/FB_IMG_1701398601483-640x426.jpg 640w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2023\/11\/FB_IMG_1701398601483.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p>Ver\u00f3n Witte consigui\u00f3 un tiempo final de 37,00 segundos, lo que le permiti\u00f3 conseguir su segunda medalla transform\u00e1ndose en la \u00fanica nadadora medallista  de la delegaci\u00f3n fueguina.<\/p>\n\n\n\n<p>El judo, de gran nivel y aporte de preseas comenz\u00f3 su competencia por equipos con un triunfo y una derrota por rama.<\/p>\n\n\n\n<p>Las chicas vencieron a Neuqu\u00e9n y cayeron con Chubut mientras que los varones superaron a Santa Cruz cediendo ante La Pampa.  Este viernes por la ma\u00f1ana concluir\u00e1 la acci\u00f3n sobre el tatami pampeano.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2023\/12\/FB_IMG_1701400635664.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2023\/12\/FB_IMG_1701400635664-1024x683.jpg\" alt=\"\" class=\"wp-image-48014\" srcset=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2023\/12\/FB_IMG_1701400635664-1024x683.jpg 1024w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2023\/12\/FB_IMG_1701400635664-300x200.jpg 300w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2023\/12\/FB_IMG_1701400635664-768x512.jpg 768w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2023\/12\/FB_IMG_1701400635664-640x427.jpg 640w, http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2023\/12\/FB_IMG_1701400635664.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p>Jueves de cierre para el atletismo con sus \u00faltimas medallas. Antonella Ojeda (Oro) y Josefina Garc\u00eda (Bronce) fueron parte del Salto en Alto consiguiendo el 1 &#8211; 3 para la provincia.<\/p>\n\n\n\n<p>En cuanto al resultado final de TDF por equipos las chicas fueron 4\u00b0 mientras que los varones ocuparon el 5\u00b0 lugar obteniendo 12 medallas, siete doradas, dos plateadas y tres de bronce.<\/p>\n\n\n\n<p>Finalmente en las disciplinas de conjunto nuevas derrotas del v\u00f3ley por 3 set a 0en ambas ramas, los varones con Chubut y las chicas frente a Neuqu\u00e9n.<\/p>\n\n\n\n<p>El b\u00e1squet cay\u00f3 en ambos casos, el femenino con Neuqu\u00e9n por 77 a 17 mientras que el masculino lo hizo 57 a 35 ante Chubut.<\/p>\n\n\n\n<p>Finalmente el f\u00fatbol se despidi\u00f3 con derrota femenina por 3 a 0 ante Neuqu\u00e9n y los muchachos cedieron con los vecinos de Santa Cruz por 2 a 0.<\/p>\n\n\n\n<p><\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 1.075<\/span><span class='epvc-label'> veces le\u00edda<\/span><\/div>\n<div class=\"jwsharethis\">\nShare this: \n<br \/>\n<a href=\"mailto:?subject=Despedida%20con%20medallas%20para%20la%20nataci%C3%B3n%20y%20el%20atletismo&amp;body=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fdespedida-con-medallas-para-la-natacion-y-el-atletismo%2F\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/email.png\" alt=\"Share this page via Email\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.stumbleupon.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fdespedida-con-medallas-para-la-natacion-y-el-atletismo%2F&amp;title=Despedida+con+medallas+para+la+nataci%C3%B3n+y+el+atletismo\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/su.png\" alt=\"Share this page via Stumble Upon\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/digg.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fdespedida-con-medallas-para-la-natacion-y-el-atletismo%2F&amp;title=Despedida+con+medallas+para+la+nataci%C3%B3n+y+el+atletismo\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/digg.png\" alt=\"Share this page via Digg this\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.facebook.com\/sharer.php?u=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fdespedida-con-medallas-para-la-natacion-y-el-atletismo%2F&amp;t=Despedida+con+medallas+para+la+nataci%C3%B3n+y+el+atletismo\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/fb.png\" alt=\"Share this page via Facebook\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/twitter.com\/intent\/tweet?text=I+like+http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fdespedida-con-medallas-para-la-natacion-y-el-atletismo%2F&amp;title=Despedida+con+medallas+para+la+nataci%C3%B3n+y+el+atletismo\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/twitter.png\" alt=\"Share this page via Twitter\" \/>\n<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Se viven los instantes finales en los Juegos EPADE de la provincia de La Pampa. Milagros Ver\u00f3n Witte fue segunda en la prueba de 50 metros pecho sumando la segunda medalla de la disciplina. El atletismo concluy\u00f3 con las medallas de \u00abAnto\u00bb Ojeda y Josefina Garc\u00eda. El judo en el cierre compite por equipos mientras &hellip; <a href=\"http:\/\/labestiadeportiva.com\/lbd\/despedida-con-medallas-para-la-natacion-y-el-atletismo\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Despedida con medallas para la nataci\u00f3n y el atletismo<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,6,2130,1],"tags":[1736,593,5178,83],"_links":{"self":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/48011"}],"collection":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/comments?post=48011"}],"version-history":[{"count":2,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/48011\/revisions"}],"predecessor-version":[{"id":48016,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/48011\/revisions\/48016"}],"wp:attachment":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media?parent=48011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/categories?post=48011"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/tags?post=48011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}