{"id":5933,"date":"2013-08-05T23:34:01","date_gmt":"2013-08-05T23:34:01","guid":{"rendered":"http:\/\/labestiadeportiva.com\/lbd\/?p=5933"},"modified":"2013-08-05T23:41:38","modified_gmt":"2013-08-05T23:41:38","slug":"superprofe-2","status":"publish","type":"post","link":"http:\/\/labestiadeportiva.com\/lbd\/superprofe-2\/","title":{"rendered":"\u00abSuperprofe\u00bb"},"content":{"rendered":"<p class=\"MsoNormal\"><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/08\/ruano.jpg\"><img loading=\"lazy\" class=\"alignleft size-full wp-image-5936\" title=\"ruano\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/08\/ruano.jpg\" alt=\"\" width=\"299\" height=\"235\" \/><\/a>El pasado viernes a media ma\u00f1ana el guardavidas local <span style=\"color: #ff0000;\">Walter Ruano<\/span> realiz\u00f3 el cruce del Canal de Beagle desde la isla Iturrieta (Argentina) hasta la baliza Bartlett (Chile). 43 minutos en las heladas aguas de entre 4 y 5 grados para recorrer alrededor de 2.000 metros, logro sin antecedentes durante la \u00e9poca invernal. <span style=\"mso-spacerun: yes;\">\u00a0<\/span>El profesor de qu\u00edmica de 47 a\u00f1os nado provisto solamente por gorro, antiparras y malla untando su cuerpo con vaselina s\u00f3lida. Desde LBD dialogamos con \u00e9l, estas son sus principales declaraciones.<!--morePara leer Click Aqu\u00ed--><\/p>\n<p class=\"MsoNormal\"><span style=\"color: #0000ff;\">\u201cEl viernes pasadas las once de la ma\u00f1ana estuvimos en isla Iturrieta (Argentina), que son m\u00e1s o menos 20 minutos de navegaci\u00f3n desde el muelle tur\u00edstico, tuvimos el apoyo de la Prefectura Naval Argentina y la Armada Chilena que se portaron de maravillas. Nade hasta la isla Bartlett en Chile, son un poquito m\u00e1s de 2.000 metros.<\/span><\/p>\n<p class=\"MsoNormal\"><span style=\"color: #0000ff;\">Siempre dependimos de las autorizaciones de Argentina y Chile por eso se fue variando la fecha y el lugar, en un principio era desde Almanza hasta Puerto Williams y nos dijeron que no porque en estos momentos en invierno son muy extremas las condiciones tanto del agua como del clima inclusive para llegar hasta Almanza entonces nos decidieron cambiar el cruce. \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/span><\/p>\n<p class=\"MsoNormal\"><span style=\"color: #0000ff;\">Ayer dios estaba de nuestra parte porque el mar estaba bien planchado, sin viento ni lluvia se dio todo y la verdad que el agua estuvo espectacular. Estuve muy bien acompa\u00f1ado por mis amigos de Eco Deportes que me hicieron el aguante todo el tiempo y una vez que entr\u00e9 en el agua lo \u00fanico que me faltaba era nadar, yo ven\u00eda entrenando hace rato, me llev\u00f3 hacerlo un poco m\u00e1s de 40 minutos mis entrenamientos previos eran de m\u00e1s de una hora en Playa Larga o detr\u00e1s del Aeropuerto as\u00ed que me sobraron poco m\u00e1s de 15 minutos de nataci\u00f3n.<\/span><\/p>\n<p class=\"MsoNormal\"><span style=\"color: #0000ff;\">La pr\u00f3xima me gustar\u00eda concretar Almanza \u2013 Puerto Williamns pero tengo que organizar con la gente de Prefectura y la Armada Chilena los tr\u00e1mites administrativos que hay que hacer y despu\u00e9s estuve hablando con los guardavidas de R\u00edo Grande para hacer un desaf\u00edo m\u00e1s grande que es cruzar el Estrecho de Magallanes por Punta Delgada.\u201d<br \/>\n<\/span><\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 958<\/span><span class='epvc-label'> veces le\u00edda<\/span><\/div>\n<div class=\"jwsharethis\">\nShare this: \n<br \/>\n<a href=\"mailto:?subject=%C2%ABSuperprofe%C2%BB&amp;body=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fsuperprofe-2%2F\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/email.png\" alt=\"Share this page via Email\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.stumbleupon.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fsuperprofe-2%2F&amp;title=%C2%ABSuperprofe%C2%BB\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/su.png\" alt=\"Share this page via Stumble Upon\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/digg.com\/submit?url=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fsuperprofe-2%2F&amp;title=%C2%ABSuperprofe%C2%BB\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/digg.png\" alt=\"Share this page via Digg this\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.facebook.com\/sharer.php?u=http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fsuperprofe-2%2F&amp;t=%C2%ABSuperprofe%C2%BB\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/fb.png\" alt=\"Share this page via Facebook\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/twitter.com\/intent\/tweet?text=I+like+http%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fsuperprofe-2%2F&amp;title=%C2%ABSuperprofe%C2%BB\">\n<img src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/twitter.png\" alt=\"Share this page via Twitter\" \/>\n<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El pasado viernes a media ma\u00f1ana el guardavidas local Walter Ruano realiz\u00f3 el cruce del Canal de Beagle desde la isla Iturrieta (Argentina) hasta la baliza Bartlett (Chile). 43 minutos en las heladas aguas de entre 4 y 5 grados para recorrer alrededor de 2.000 metros, logro sin antecedentes durante la \u00e9poca invernal. \u00a0El profesor &hellip; <a href=\"http:\/\/labestiadeportiva.com\/lbd\/superprofe-2\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">\u00abSuperprofe\u00bb<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":5936,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,60,1],"tags":[817,20,818],"_links":{"self":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/5933"}],"collection":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/comments?post=5933"}],"version-history":[{"count":3,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/5933\/revisions"}],"predecessor-version":[{"id":5938,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/5933\/revisions\/5938"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media\/5936"}],"wp:attachment":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media?parent=5933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/categories?post=5933"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/tags?post=5933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}