{"id":3188,"count":3,"description":"","link":"http:\/\/labestiadeportiva.com\/lbd\/tag\/40o-nacional-de-selecciones-a\/","name":"40\u00ba Nacional de Selecciones \"A\"","slug":"40o-nacional-de-selecciones-a","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/tags\/3188"}],"collection":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts?tags=3188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}