{"id":11455,"date":"2014-07-01T03:44:17","date_gmt":"2014-07-01T03:44:17","guid":{"rendered":"http:\/\/labestiadeportiva.com\/lbd\/?p=11455"},"modified":"2014-07-01T03:44:17","modified_gmt":"2014-07-01T03:44:17","slug":"gran-semana-de-leo-mayer-en-wimbledon","status":"publish","type":"post","link":"https:\/\/labestiadeportiva.com\/lbd\/gran-semana-de-leo-mayer-en-wimbledon\/","title":{"rendered":"Gran semana de Leo Mayer en Wimbledon"},"content":{"rendered":"<p>Por Mat\u00edas Pouso (Corresponsal LBD en la Ciudad Aut\u00f3noma de Buenos Aires)<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/07\/mayerwimb20141.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-11457\" title=\"mayerwimb2014\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/07\/mayerwimb20141-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/07\/mayerwimb20141-300x169.jpg 300w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/07\/mayerwimb20141.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>El tenista correntino qued\u00f3 eliminado en octavos de final del tercer Grand Slam de la temporada a manos del b\u00falgaro Grigor Dimitrov, sin embargo redonde\u00f3 una muy buena actuaci\u00f3n en el torneo m\u00e1s tradicional del circuito.<\/p>\n<p>La realidad del tenis argentino sigue siendo que ning\u00fan jugador se adapta completamente al r\u00e1pido c\u00e9sped sobre el que se disputa tan solo un mes de competencia al a\u00f1o.<!--more--><\/p>\n<p>Los casos de David Nalbandian y de Juan Mart\u00edn Del Potro siguen siendo extraordinarios ya que al ser dos tenistas todoterreno pudieron conseguir grandes resultados en cada una de las superficies que pisaron, incluidos una final (Nalbandian en 2002) y una semifinal (Del Potro en 2013) sobre el pasto londinense.<\/p>\n<p>Los octavos de final alcanzados por Leo Mayer, tambi\u00e9n quedar\u00e1n dentro de los gratos recuerdos ten\u00edsticos nacionales. El resultado final fue 6-4, 7-6 (6) y 6-2 en favor de Dimitrov, a pesar de haber sido una victoria en set corridos, no fue nada f\u00e1cil para el b\u00falgaro de 23 a\u00f1os.<\/p>\n<p>En el primer set, la peque\u00f1a diferencia fue tan solo un quiebre en favor del europeo. El mismo lleg\u00f3 por culpa de los siete errores no forzados cometidos por Mayer contra los tres que realiz\u00f3 su rival. La paridad se quebr\u00f3 reci\u00e9n en el 4-4, cuando Dimitrov aprovech\u00f3 uno de los dos puntos de quiebre con los que cont\u00f3.<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/07\/djokowimb2014-copia.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-11462\" title=\"djokowimb2014 - copia\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/07\/djokowimb2014-copia-300x174.jpg\" alt=\"\" width=\"300\" height=\"174\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/07\/djokowimb2014-copia-300x174.jpg 300w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/07\/djokowimb2014-copia.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>En la segunda manga, el empate se extendi\u00f3 hasta el tie-break. Fueron seis saques ganadores para Mayer, cuatro para Dimitrov y 14 winners para cada uno. Sin embargo, el set fue para el n\u00famero 13 del ranking en el desempate tras imponerse por la m\u00ednima diferencia (8-6).<\/p>\n<p>Ya en el \u00faltimo parcial, el clon de Federer fue contundente y sentenci\u00f3 el resultado con un 6-2 para eliminar al \u00faltimo argentino que quedaba en competencia en el All England.<\/p>\n<p>Mayer halag\u00f3 el elegante juego de Dimitrov, que pareciera ser un calco del mejor jugador de todos los tiempos. <span style=\"color: #0000ff;\">\u00abTe cambian a uno por el otro y no te das cuenta\u00bb<\/span> hab\u00eda declarado el correntino.<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/07\/173044844-andy-murray-wimbledon_custom-35f2fcba3fc56969d81edf44ccb851e47aced7cd-s6-c30.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-11464\" title=\"173044844-andy-murray-wimbledon_custom-35f2fcba3fc56969d81edf44ccb851e47aced7cd-s6-c30\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/07\/173044844-andy-murray-wimbledon_custom-35f2fcba3fc56969d81edf44ccb851e47aced7cd-s6-c30-180x300.jpg\" alt=\"\" width=\"180\" height=\"300\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/07\/173044844-andy-murray-wimbledon_custom-35f2fcba3fc56969d81edf44ccb851e47aced7cd-s6-c30-180x300.jpg 180w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/07\/173044844-andy-murray-wimbledon_custom-35f2fcba3fc56969d81edf44ccb851e47aced7cd-s6-c30-615x1024.jpg 615w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/07\/173044844-andy-murray-wimbledon_custom-35f2fcba3fc56969d81edf44ccb851e47aced7cd-s6-c30.jpg 948w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><\/a>Dos de los m\u00e1ximos candidatos ya est\u00e1n en cuartos de final, Novak Djokovic y Andy Murray vencieron a Tsonga y a Kevin Anderson respectivamente para instalarse entre los mejores ocho. El serbio se enfrentar\u00e1 al croata Marin Cilic y el brit\u00e1nico har\u00e1 lo propio contra Dimitrov.<\/p>\n<p>Por el lado bajo del cuadro, Stan Wawrinka enfrentar\u00e1 a Feliciano L\u00f3pez, el vencedor de este encuentro se medir\u00e1 con el ganador del duelo entre Tommy Robredo y Roger Federer.<\/p>\n<p>En tanto que Rafael Nadal ir\u00e1 por un lugar en cuartos enfrentando al australiano Nick Kyrgios, lo mismo har\u00e1 Kei Nishikori frente a Milos Raonic.<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/07\/Leonardo+Mayer+Wimbledon+Tennis+Championships+FwCqI3b5MIox.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-11465\" title=\"Leonardo+Mayer+Wimbledon+Tennis+Championships+FwCqI3b5MIox\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/07\/Leonardo+Mayer+Wimbledon+Tennis+Championships+FwCqI3b5MIox-300x210.jpg\" alt=\"\" width=\"300\" height=\"210\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/07\/Leonardo+Mayer+Wimbledon+Tennis+Championships+FwCqI3b5MIox-300x210.jpg 300w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2014\/07\/Leonardo+Mayer+Wimbledon+Tennis+Championships+FwCqI3b5MIox.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 1.175<\/span><span class='epvc-label'> veces le\u00edda<\/span><\/div>\n<div class=\"jwsharethis\">\nShare this: \n<br \/>\n<a href=\"mailto:?subject=Gran%20semana%20de%20Leo%20Mayer%20en%20Wimbledon&amp;body=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fgran-semana-de-leo-mayer-en-wimbledon%2F\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/email.png\" alt=\"Share this page via Email\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.stumbleupon.com\/submit?url=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fgran-semana-de-leo-mayer-en-wimbledon%2F&amp;title=Gran+semana+de+Leo+Mayer+en+Wimbledon\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/su.png\" alt=\"Share this page via Stumble Upon\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/digg.com\/submit?url=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fgran-semana-de-leo-mayer-en-wimbledon%2F&amp;title=Gran+semana+de+Leo+Mayer+en+Wimbledon\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/digg.png\" alt=\"Share this page via Digg this\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fgran-semana-de-leo-mayer-en-wimbledon%2F&amp;t=Gran+semana+de+Leo+Mayer+en+Wimbledon\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/fb.png\" alt=\"Share this page via Facebook\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/twitter.com\/intent\/tweet?text=I+like+https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fgran-semana-de-leo-mayer-en-wimbledon%2F&amp;title=Gran+semana+de+Leo+Mayer+en+Wimbledon\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/twitter.png\" alt=\"Share this page via Twitter\" \/>\n<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por Mat\u00edas Pouso (Corresponsal LBD en la Ciudad Aut\u00f3noma de Buenos Aires) El tenista correntino qued\u00f3 eliminado en octavos de final del tercer Grand Slam de la temporada a manos del b\u00falgaro Grigor Dimitrov, sin embargo redonde\u00f3 una muy buena actuaci\u00f3n en el torneo m\u00e1s tradicional del circuito. La realidad del tenis argentino sigue siendo &hellip; <a href=\"https:\/\/labestiadeportiva.com\/lbd\/gran-semana-de-leo-mayer-en-wimbledon\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Gran semana de Leo Mayer en Wimbledon<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":11457,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6,1,39],"tags":[4835,1563],"_links":{"self":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/11455"}],"collection":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/comments?post=11455"}],"version-history":[{"count":1,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/11455\/revisions"}],"predecessor-version":[{"id":11466,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/11455\/revisions\/11466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media\/11457"}],"wp:attachment":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media?parent=11455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/categories?post=11455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/tags?post=11455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}