{"id":14689,"date":"2015-03-06T11:53:20","date_gmt":"2015-03-06T14:53:20","guid":{"rendered":"http:\/\/labestiadeportiva.com\/lbd\/?p=14689"},"modified":"2015-03-06T14:08:39","modified_gmt":"2015-03-06T17:08:39","slug":"lidera-el-campeon","status":"publish","type":"post","link":"https:\/\/labestiadeportiva.com\/lbd\/lidera-el-campeon\/","title":{"rendered":"Lidera el campe\u00f3n"},"content":{"rendered":"<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/03\/10945409_10153075133049827_3901082546008134842_n1.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-14691\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/03\/10945409_10153075133049827_3901082546008134842_n1-300x138.jpg\" alt=\"10945409_10153075133049827_3901082546008134842_n\" width=\"300\" height=\"138\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/03\/10945409_10153075133049827_3901082546008134842_n1-300x138.jpg 300w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/03\/10945409_10153075133049827_3901082546008134842_n1.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Se disput\u00f3 la segunda fecha del torneo oficial de rugby organizado por la URTF para planteles superiores. En R\u00edo Grande triunfaron URC y Orcas mientras que en la capital provincial Las \u00c1guilas dobleg\u00f3 al Club Colegio del Sur. El \u201cFucsia\u201d manda con diez puntos escoltado por el \u201cTricolor\u201d a tan solo una unidad. La foto principal es gentileza de \u201cCachi\u201d Gestido.<!--more--><\/p>\n<p>El pasado s\u00e1bado se realiz\u00f3 la segunda jornada oficial de primera divisi\u00f3n para el rugby fueguino. La programaci\u00f3n entreg\u00f3 dos partidos en el norte de la isla y uno en Ushuaia.<\/p>\n<p>En la capital el encuentro se desarrollo en la cancha \u201cGerardo Hiriart\u201d ubicada en el ex Centro H\u00edpico Fin del Mundo hoy sede del Club Colegio del Sur.<\/p>\n<p>Hasta all\u00ed lleg\u00f3 el \u00faltimo campe\u00f3n de la categor\u00eda, Las \u00c1guilas, quien se impuso por un claro 29 a 0.<\/p>\n<p>En R\u00edo Grande Orcas logr\u00f3 cerrar una victoria ante el debutante Sindicato de Camioneros por 15 a 10 mientras que en el juego m\u00e1s esperado URC consigui\u00f3 una resonante victoria ante el R\u00edo Grande RHC por 17 a 15 en un cambiante partido donde la diferencia solo estuvo en la certeza a la hora de las conversiones.<\/p>\n<p>Este fin de semana se disputar\u00e1 la tercera fecha con partidos a las 15 y 17 horas. Un Ushuaia URC se medir\u00e1 ante el club Colegio del Sur el s\u00e1bado a las cinco de la tarde mientras que Las \u00c1guilas y R\u00edo Grande RHC lo har\u00e1n el d\u00eda domingo a las tres. Asimismo en R\u00edo Grande Universitario recibir\u00e1 a Orcas durante la jornada sabatina a partir de las 15 quedando libre el club Sindicato de Camioneros.<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/03\/1513678_733961056720894_3986819412541877203_n.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-14692\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/03\/1513678_733961056720894_3986819412541877203_n-300x225.jpg\" alt=\"1513678_733961056720894_3986819412541877203_n\" width=\"300\" height=\"225\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/03\/1513678_733961056720894_3986819412541877203_n-300x225.jpg 300w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/03\/1513678_733961056720894_3986819412541877203_n.jpg 526w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><span style=\"color: #0000ff;\">Resultados 2\u00b0 Fecha<\/span><br \/>\nClub Colegio del Sur 0 Las \u00c1guilas 29<br \/>\nR\u00edo Grande RHC 15 URC 17<br \/>\nSindicato de Camioneros 10 Orcas 15<\/p>\n<p><span style=\"color: #0000ff;\">Posiciones Actualizadas<\/span><br \/>\nEquipos PJ Pts.<br \/>\n<span style=\"color: #ff0000;\">Las \u00c1guilas 2 10<\/span><br \/>\nURC 2 9<br \/>\nUniversitario 1 4<br \/>\nOrcas 2 4<br \/>\nR\u00edo Grande RHC 1 1<br \/>\nCamioneros 2 1<br \/>\nClub Colegio del Sur 2 0<\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 1.169<\/span><span class='epvc-label'> veces le\u00edda<\/span><\/div>\n<div class=\"jwsharethis\">\nShare this: \n<br \/>\n<a href=\"mailto:?subject=Lidera%20el%20campe%C3%B3n&amp;body=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Flidera-el-campeon%2F\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/email.png\" alt=\"Share this page via Email\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.stumbleupon.com\/submit?url=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Flidera-el-campeon%2F&amp;title=Lidera+el+campe%C3%B3n\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/su.png\" alt=\"Share this page via Stumble Upon\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/digg.com\/submit?url=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Flidera-el-campeon%2F&amp;title=Lidera+el+campe%C3%B3n\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/digg.png\" alt=\"Share this page via Digg this\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Flidera-el-campeon%2F&amp;t=Lidera+el+campe%C3%B3n\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/fb.png\" alt=\"Share this page via Facebook\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/twitter.com\/intent\/tweet?text=I+like+https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Flidera-el-campeon%2F&amp;title=Lidera+el+campe%C3%B3n\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/twitter.png\" alt=\"Share this page via Twitter\" \/>\n<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Se disput\u00f3 la segunda fecha del torneo oficial de rugby organizado por la URTF para planteles superiores. En R\u00edo Grande triunfaron URC y Orcas mientras que en la capital provincial Las \u00c1guilas dobleg\u00f3 al Club Colegio del Sur. El \u201cFucsia\u201d manda con diez puntos escoltado por el \u201cTricolor\u201d a tan solo una unidad. La foto &hellip; <a href=\"https:\/\/labestiadeportiva.com\/lbd\/lidera-el-campeon\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Lidera el campe\u00f3n<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":14691,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,1],"tags":[242,108,190,451,191],"_links":{"self":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/14689"}],"collection":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/comments?post=14689"}],"version-history":[{"count":4,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/14689\/revisions"}],"predecessor-version":[{"id":14696,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/14689\/revisions\/14696"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media\/14691"}],"wp:attachment":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media?parent=14689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/categories?post=14689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/tags?post=14689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}