{"id":15984,"date":"2015-06-08T16:05:16","date_gmt":"2015-06-08T19:05:16","guid":{"rendered":"http:\/\/labestiadeportiva.com\/lbd\/?p=15984"},"modified":"2015-06-08T16:05:16","modified_gmt":"2015-06-08T19:05:16","slug":"tres-veces-barca","status":"publish","type":"post","link":"https:\/\/labestiadeportiva.com\/lbd\/tres-veces-barca\/","title":{"rendered":"Tres veces Bar\u00e7a"},"content":{"rendered":"<p>Por Daniel Campos (Corresponsal LBD en Palma de Mallorca, Espa\u00f1a)<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/06\/bcn15a.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-15985\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/06\/bcn15a-300x199.jpg\" alt=\"bcn15a\" width=\"300\" height=\"199\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/06\/bcn15a-300x199.jpg 300w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/06\/bcn15a.jpg 630w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>El F\u00fatbol Club Barcelona completa un fin de temporada ideal a al sumar su tercer t\u00edtulo consecutivo, Liga, Copa del Rey y Champions. En el estadio Ol\u00edmpico de Berl\u00edn venci\u00f3 por 3 a 1 al Juventus de Tur\u00edn. Los catalanes iban por su quinta orejona y los italianos por\u00a0 su tercera, pero el trofeo europeo por excelencia se fue a la ciudad condal.<!--more--><\/p>\n<p>El conjunto dirigido por Luis Enrique tuvo el control del partido, si bien Messi se qued\u00f3 sin marcar, fue desequilibrante en muchas jugadas. Marc\u00f3 el ritmo del cotejo, con pases en diagonal de m\u00e1s de 30 metros y manejando el contragolpe como mejor sabe hacerlo el argentino.<\/p>\n<p>Pero fue desde el inicio mismo que el Barcelona confirm\u00f3 su condici\u00f3n de favorito, en el minuto 3 Rakitic con zurda bate a Buffon tras un pase de Iniesta.<\/p>\n<p>Lo que sigui\u00f3 fueron quince minutos de puro Bar\u00e7a, los de Allegri no estaban muy c\u00f3modos en el terreno de juego y los blaugranas perdonaron la vida a los turineses y as\u00ed se fueron al descanso.<\/p>\n<p>A los cinco minutos de la segunda parte Morata aprovech\u00f3 un rechace de Ter Stegen y pus\u00f3 la igualdad en el marcador y otra vez vuelta a empezar.<\/p>\n<p>Aparecieron en escena Tevez, Pogba y Marchisio pero no alcanz\u00f3 para noquear a los blaugranas que acusaron el golpe. Pero en el minuto 68 Su\u00e1rez remat\u00f3 un tras un despeje de Buffon.<\/p>\n<p>Por fin el uruguayo logro su objetivo de batir al portero italiano que le hab\u00eda parado todos sus disparos. La Juve no baj\u00f3 los brazos y sigui\u00f3 porfiando de cara al arco rival.<\/p>\n<p>Pero la entrada de Xavi Hern\u00e1ndez puso un poco de orden en el campo de juego y el Bar\u00e7a se dedic\u00f3 a defender el resultado y jugando con la desesperaci\u00f3n de los juventinos.<\/p>\n<p>En el tiempo de descuento Pedro cedi\u00f3 para Neymar Jr y el brasile\u00f1o que anteriormente vio como el juez turco C\u00fcneyt \u00c7akir, le anulaba correctamente un gol con la mano, empujaba el bal\u00f3n al fondo de la red. Final y fiesta en Berl\u00edn, el Barcelona campe\u00f3n de la Champions.<\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 1.255<\/span><span class='epvc-label'> veces le\u00edda<\/span><\/div>\n<div class=\"jwsharethis\">\nShare this: \n<br \/>\n<a href=\"mailto:?subject=Tres%20veces%20Bar%C3%A7a&amp;body=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Ftres-veces-barca%2F\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/email.png\" alt=\"Share this page via Email\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.stumbleupon.com\/submit?url=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Ftres-veces-barca%2F&amp;title=Tres+veces+Bar%C3%A7a\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/su.png\" alt=\"Share this page via Stumble Upon\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/digg.com\/submit?url=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Ftres-veces-barca%2F&amp;title=Tres+veces+Bar%C3%A7a\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/digg.png\" alt=\"Share this page via Digg this\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Ftres-veces-barca%2F&amp;t=Tres+veces+Bar%C3%A7a\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/fb.png\" alt=\"Share this page via Facebook\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/twitter.com\/intent\/tweet?text=I+like+https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Ftres-veces-barca%2F&amp;title=Tres+veces+Bar%C3%A7a\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/twitter.png\" alt=\"Share this page via Twitter\" \/>\n<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por Daniel Campos (Corresponsal LBD en Palma de Mallorca, Espa\u00f1a) El F\u00fatbol Club Barcelona completa un fin de temporada ideal a al sumar su tercer t\u00edtulo consecutivo, Liga, Copa del Rey y Champions. En el estadio Ol\u00edmpico de Berl\u00edn venci\u00f3 por 3 a 1 al Juventus de Tur\u00edn. Los catalanes iban por su quinta orejona &hellip; <a href=\"https:\/\/labestiadeportiva.com\/lbd\/tres-veces-barca\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Tres veces Bar\u00e7a<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":15985,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,14,1],"tags":[104,233,17,83],"_links":{"self":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/15984"}],"collection":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/comments?post=15984"}],"version-history":[{"count":1,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/15984\/revisions"}],"predecessor-version":[{"id":15986,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/15984\/revisions\/15986"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media\/15985"}],"wp:attachment":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media?parent=15984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/categories?post=15984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/tags?post=15984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}