{"id":17420,"date":"2015-09-28T15:14:48","date_gmt":"2015-09-28T18:14:48","guid":{"rendered":"http:\/\/labestiadeportiva.com\/lbd\/?p=17420"},"modified":"2015-09-28T15:14:48","modified_gmt":"2015-09-28T18:14:48","slug":"el-crack-de-messi","status":"publish","type":"post","link":"https:\/\/labestiadeportiva.com\/lbd\/el-crack-de-messi\/","title":{"rendered":"El crack de Messi"},"content":{"rendered":"<p>Por Daniel Campos (Corresponsal LBD en Palma de Mallorca, Espa\u00f1a)<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/09\/leolesyon.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-17421\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/09\/leolesyon-300x158.jpg\" alt=\"leolesyon\" width=\"300\" height=\"158\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/09\/leolesyon-300x158.jpg 300w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2015\/09\/leolesyon.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>En la Liga el nuevo l\u00edder es el Villarreal que gan\u00f3 por la m\u00ednima diferencia al Atl\u00e9tico de Madrid. Los blancos no pasaron del empate ante el M\u00e1laga y el Bar\u00e7a gan\u00f3 en el Camp Nou, pero pierde a Messi por lesi\u00f3n, que tiene para dos meses. Aqu\u00ed el resumen del fin de semana.<!--more--><\/p>\n<p>Viernes por la noche comenz\u00f3 a rodar el bal\u00f3n en Espa\u00f1a con el cruce entre el Valencia y el Granada. Un gol del alem\u00e1n Shkodran Mustafi en el minuto 27 dio el triunfo al equipo de Nuno Espirito Santo, un poco de ox\u00edgeno para el t\u00e9cnico local muy cuestionado esta semana por la afici\u00f3n \u201cche\u201d.<\/p>\n<p>Fue 1 a 0 para el Valencia sobre el Granada, los andaluces siguen en la zona baja de la tabla. El s\u00e1bado por la tarde, en el Camp Nou una victoria agridulce del Barcelona ante Las Palmas. Fue 2 a 1 para los blaugranas. El argentino Leo Messi se retir\u00f3 a poco de comenzar el partido por una\u00a0 grave lesi\u00f3n, seg\u00fan el parte m\u00e9dico del club catal\u00e1n, se trata de una rotura del ligamento colateral interno.<\/p>\n<p>Se estima que estar\u00e1 de baja unas ocho semanas. En lo que se refiere al encuentro, Luis Suar\u00e9z anot\u00f3 los dos tantos del Bar\u00e7a y Viera, el descuento canario. Neymar Jr. fall\u00f3 un tiro libre penal. En el siguiente turno, un empate sin goles fue el resultado final entre el Real Madrid y el M\u00e1laga.<\/p>\n<p>Un enorme Kameni par\u00f3 todo lo que le tiraron y dej\u00f3 tocada la moral del equipo blanco ante su p\u00fablico. Si bien el conjunto malague\u00f1o rescat\u00f3 un punto en su visita al Bernab\u00e9u sigue sin marcar en la Liga. En el Madrigal un solitario gol de Baptistao en el primer cuarto de juego, sirvi\u00f3 para dar los tres puntos y liderato del torneo al Villarreal en su cruce ante el Atl\u00e9tico de Madrid.<\/p>\n<p>A la misma hora en el sur de Espa\u00f1a, primera victoria y muy trabajada del Sevilla frente al Rayo Vallecano. Los andaluces siempre dominaron gran parte del cotejo, pero los madrile\u00f1os vendieron muy cara su derrota en el S\u00e1nchez Pizju\u00e1n. Los goles del local, Gameiro, N-Zonzi y Kodaplayka.<\/p>\n<p>Por el lado rayista, Bebe y Javi Guerra.\u00a0 Cerrando la noche del s\u00e1bado, empate 1 a 1 en Ipur\u00faa, entre Eibar y Celta de Vigo. Borja Bast\u00f3n a los tres minutos del primer tiempo aprovech\u00f3 un error de la defensa gallega y anot\u00f3 el primero.<\/p>\n<p>No fue hasta el minuto 76 en que Iago Aspas igual\u00f3 el marcador para que el Celta siga una semana m\u00e1s en lo alto de la clasificaci\u00f3n. Al d\u00eda siguiente, domingo al mediod\u00eda, el Sporting en su estadio gan\u00f3 al Betis por 2 a 1. Carlos y Rub\u00e9n Castro dieron el triunfo al representativo asturiano y descont\u00f3 para los b\u00e9ticos Joaqu\u00edn.<\/p>\n<p>Turno tarde y el Deportivo super\u00f3 claramente al Espanyol. En Riazor abri\u00f3 la cuenta \u00c1lvaro en contra para los coru\u00f1enses, y luego Lucas P\u00e9rez en dos ocasiones sell\u00f3 el 3 a 0. A continuaci\u00f3n, en el Alfonso P\u00e9rez, el Getafe gole\u00f3 por 3 a 0 al Levante.<\/p>\n<p>Los tres tantos del equipo azul\u00f3n llegaron en los \u00faltimos minutos de la segunda parte de la mano de \u00c1lvaro V\u00e1zquez, por partida doble, y Emiliano Buend\u00eda. Cerrando la sexta jornada del f\u00fatbol de primera, en Anoeta, cl\u00e1sico vasco entre la Real Sociedad y el Athletic de Bilbao se sald\u00f3 con un empate sin goles.<\/p>\n<p>&nbsp;<\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 1.136<\/span><span class='epvc-label'> veces le\u00edda<\/span><\/div>\n<div class=\"jwsharethis\">\nShare this: \n<br \/>\n<a href=\"mailto:?subject=El%20crack%20de%20Messi&amp;body=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fel-crack-de-messi%2F\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/email.png\" alt=\"Share this page via Email\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.stumbleupon.com\/submit?url=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fel-crack-de-messi%2F&amp;title=El+crack+de+Messi\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/su.png\" alt=\"Share this page via Stumble Upon\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/digg.com\/submit?url=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fel-crack-de-messi%2F&amp;title=El+crack+de+Messi\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/digg.png\" alt=\"Share this page via Digg this\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fel-crack-de-messi%2F&amp;t=El+crack+de+Messi\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/fb.png\" alt=\"Share this page via Facebook\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/twitter.com\/intent\/tweet?text=I+like+https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fel-crack-de-messi%2F&amp;title=El+crack+de+Messi\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/twitter.png\" alt=\"Share this page via Twitter\" \/>\n<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por Daniel Campos (Corresponsal LBD en Palma de Mallorca, Espa\u00f1a) En la Liga el nuevo l\u00edder es el Villarreal que gan\u00f3 por la m\u00ednima diferencia al Atl\u00e9tico de Madrid. Los blancos no pasaron del empate ante el M\u00e1laga y el Bar\u00e7a gan\u00f3 en el Camp Nou, pero pierde a Messi por lesi\u00f3n, que tiene para &hellip; <a href=\"https:\/\/labestiadeportiva.com\/lbd\/el-crack-de-messi\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">El crack de Messi<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":17421,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,14,1],"tags":[17,35,83],"_links":{"self":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/17420"}],"collection":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/comments?post=17420"}],"version-history":[{"count":1,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/17420\/revisions"}],"predecessor-version":[{"id":17422,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/17420\/revisions\/17422"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media\/17421"}],"wp:attachment":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media?parent=17420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/categories?post=17420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/tags?post=17420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}