{"id":2050,"date":"2012-12-11T14:29:00","date_gmt":"2012-12-11T14:29:00","guid":{"rendered":"http:\/\/labestiadeportiva.com\/lbd\/?p=2050"},"modified":"2012-12-12T16:43:34","modified_gmt":"2012-12-12T16:43:34","slug":"la-punta-pude-cambiar-entre-semana","status":"publish","type":"post","link":"https:\/\/labestiadeportiva.com\/lbd\/la-punta-pude-cambiar-entre-semana\/","title":{"rendered":"La punta puede cambiar entre semana"},"content":{"rendered":"<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2012\/12\/MG_0522.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-2051\" title=\"_MG_0522\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2012\/12\/MG_0522-300x163.jpg\" alt=\"\" width=\"300\" height=\"163\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2012\/12\/MG_0522-300x163.jpg 300w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2012\/12\/MG_0522.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Camioneros tan solo empat\u00f3 sin goles ante Juventud del Sur y si este jueves por la noche Los Cuervos FDM vence a Los Andes Jrs. cuando dispute su partido postergado volver\u00e1 a ser l\u00edder. Golearon Centro Galicia y Mutual BTF mientras que Mercantil sum\u00f3 de a tres sin jugar pues Libertad no complet\u00f3 el equipo. En la B el puntero, La UOM, sac\u00f3 algo m\u00e1s de ventaja aprovechando el empate de Lasserre. La 8\u00b0 fecha se juega durante la semana a partir de hoy, martes.<!--morePara leer Click Aqu\u00ed--><\/p>\n<p>El torneo oficial de primera divisi\u00f3n \u201cFeliciano Genes\u201d organizado por la Liga Ushuaiense no da respiro. Todo comenz\u00f3 con el triunfo de G\u00fcemes por 1 a 0 sobre CAEF,\u00a0 los hombres de verde se acomodan en la tercera ubicaci\u00f3n de la tabla aunque muy lejos del puntero mientras que el juvenil equipo de CAEF no logra salir del fondo de las posiciones donde solo supera a Magallanes.<\/p>\n<p>En otro de los partidos de la B El Fort\u00edn super\u00f3 a Les Eclaireurs 3 a 1, estos dos equipos marchan en la mitad de tabla. Lago Escondido le propin\u00f3 al \u00faltimo de la tabla Magallanes la primera goleada del fin de semana, fue 9 a 0 que no merece ning\u00fan tipo de an\u00e1lisis.\u00a0 Como si fuera contagioso, lo de las goleadas, en el primer partido de la principal categor\u00eda Centro Galicia derrot\u00f3 categ\u00f3ricamente a El Porvenir por 8 a 0.<\/p>\n<p>Mercantil sum\u00f3 sin esfuerzo dado que los muchachos de Libertad no pudieron completar el equipo, hasta el momento la campa\u00f1a de los mercantiles es muy buena ubic\u00e1ndose terceros con trece unidades. A mitad de la tarde del domingo Mutual BTF se enfrent\u00f3 al siempre complicado Arturo Prat, luego de un primer tiempo para el olvido donde los bancarios cayeron por 2 a 0 se recuperaron en el complemento para triunfar por 5 a 2 y continuar en una posici\u00f3n expectante en la tabla.<\/p>\n<p>El partido esperado lleg\u00f3 a la hora del t\u00e9, Camioneros y Juventud empataron sin goles en un encuentro donde los de Ralinqueo estuvieron m\u00e1s cerca de la victoria. El punto parece no servir de mucho, para Juventud llega a 5 unidades alcanzando a Prat pero cerca del fondo mientras que los transportistas le dejan libre el camino de la punta a Los Cuervos que de ganar el jueves volver\u00e1n a mirar a todos desde arriba.<\/p>\n<p>En la B La UOM volvi\u00f3 a mostrar la contundencia de siempre al ganarle a Campolter por 5 a 3. El cierre de la fecha entreg\u00f3 la igualdad en un gol entre dos juveniles planteles los de Lasserre y Andes del Sur. Desde este martes por la noche continuar\u00e1 la actividad oficial sobre el sint\u00e9tico del \u201cHugo Lumbreras\u201d.<\/p>\n<p>Resultados<br \/>\n1\u00b0 B\u00a0 CAEF 0\u00a0 G\u00fcemes\u00a0 1<br \/>\n1\u00b0 B\u00a0 El Fort\u00edn\u00a0 3\u00a0 Les Eclaireurs\u00a0 1<br \/>\n1\u00b0 B\u00a0 Lago Escondido\u00a0 9\u00a0\u00a0 \u00a0Magallanes\u00a0 0<br \/>\n1\u00b0 A\u00a0 Centro Galicia\u00a0 8\u00a0\u00a0 \u00a0El Porvenir\u00a0 0<br \/>\n1\u00b0 A\u00a0 Libertad\u00a0 0\u00a0\u00a0 \u00a0 Mercantil\u00a0 1<br \/>\n1\u00b0 A\u00a0 Mutual BTF\u00a0 5\u00a0 Arturo Prat\u00a0 2<br \/>\n1\u00b0 A\u00a0 Camioneros\u00a0 0\u00a0 Juventud del Sur\u00a0 0<br \/>\n1\u00b0 B\u00a0 Campolter\u00a0 3\u00a0 La UOM 5<br \/>\n1\u00b0 B\u00a0 Lasserre\u00a0 1\u00a0 Andes del Sur\u00a0 1<\/p>\n<p>Posiciones Actualizadas<br \/>\nPrimera \u201cA\u201d<br \/>\nEquipos\u00a0 PJ\u00a0\u00a0\u00a0 Pts.<br \/>\n<span style=\"color: #ff0000;\">Camioneros\u00a0 7\u00a0\u00a0\u00a0 17\u00a0\u00a0\u00a0\u00a0 \u00a0<\/span><br \/>\nLos Cuervos FDM 6\u00a0\u00a0 15<br \/>\nMercantil 7\u00a0\u00a0\u00a0 13<br \/>\nLos Andes Jrs.\u00a0 6\u00a0\u00a0\u00a0\u00a0 12<br \/>\nCentro Galicia\u00a0 7\u00a0\u00a0\u00a0\u00a0 12<br \/>\nMutual BTF\u00a0 7\u00a0 12<br \/>\nArturo Prat\u00a0 7\u00a0 5<br \/>\nJuventud del Sur 7\u00a0 \u00a0 5<br \/>\nLibertad\u00a0 7\u00a0 4<br \/>\nEl Porvenir\u00a0 7\u00a0 3<\/p>\n<p>Primera \u201cB\u201d<br \/>\nEquipos PJ\u00a0 Pts.<br \/>\n<span style=\"color: #ff0000;\">La UOM\u00a0 7\u00a0\u00a0 21\u00a0\u00a0 \u00a0<\/span><br \/>\nLasserre 7\u00a0\u00a0 16<br \/>\nEl Fort\u00edn 6\u00a0\u00a0\u00a0 10<br \/>\nL. Escondido 6\u00a0\u00a0\u00a0 10<br \/>\nG\u00fcemes\u00a0 7\u00a0 9<br \/>\nAndes del Sur 7\u00a0 8<br \/>\nLes Eclaireurs 6\u00a0\u00a0\u00a0 7<br \/>\nCam.Pol.Ter 7\u00a0\u00a0\u00a0 6<br \/>\nEl Duende\u00a0 5\u00a0 6<br \/>\nCAEF\u00a0 6\u00a0 5<br \/>\nMagallanes 6\u00a0 0<br \/>\nPr\u00f3xima Fecha (8\u00b0)<br \/>\nMartes\u00a0 11<br \/>\n22.00 1\u00b0 A\u00a0 Arturo Prat\u00a0 &#8211;\u00a0 Mercantil<br \/>\nMi\u00e9rcoles 12<br \/>\n21.40 1\u00b0 A\u00a0 Mutual BTF\u00a0 &#8211;\u00a0 El Porvenir<br \/>\nJueves\u00a0 13<br \/>\n19.40 1\u00b0 B\u00a0 G\u00fcemes\u00a0 &#8211; Campolter<br \/>\n21.40 1\u00b0 A\u00a0 Los Andes Jrs. &#8211; Los Cuervos FDM (7\u00b0 fecha)<br \/>\nViernes\u00a0 14<br \/>\n21.30 1\u00b0 A\u00a0 Libertad\u00a0 &#8211; Juventud del Sur<\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 1.006<\/span><span class='epvc-label'> veces le\u00edda<\/span><\/div>\n<div class=\"jwsharethis\">\nShare this: \n<br \/>\n<a href=\"mailto:?subject=La%20punta%20puede%20cambiar%20entre%20semana&amp;body=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fla-punta-pude-cambiar-entre-semana%2F\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/email.png\" alt=\"Share this page via Email\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.stumbleupon.com\/submit?url=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fla-punta-pude-cambiar-entre-semana%2F&amp;title=La+punta+puede+cambiar+entre+semana\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/su.png\" alt=\"Share this page via Stumble Upon\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/digg.com\/submit?url=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fla-punta-pude-cambiar-entre-semana%2F&amp;title=La+punta+puede+cambiar+entre+semana\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/digg.png\" alt=\"Share this page via Digg this\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fla-punta-pude-cambiar-entre-semana%2F&amp;t=La+punta+puede+cambiar+entre+semana\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/fb.png\" alt=\"Share this page via Facebook\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/twitter.com\/intent\/tweet?text=I+like+https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fla-punta-pude-cambiar-entre-semana%2F&amp;title=La+punta+puede+cambiar+entre+semana\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/twitter.png\" alt=\"Share this page via Twitter\" \/>\n<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Camioneros tan solo empat\u00f3 sin goles ante Juventud del Sur y si este jueves por la noche Los Cuervos FDM vence a Los Andes Jrs. cuando dispute su partido postergado volver\u00e1 a ser l\u00edder. Golearon Centro Galicia y Mutual BTF mientras que Mercantil sum\u00f3 de a tres sin jugar pues Libertad no complet\u00f3 el equipo. &hellip; <a href=\"https:\/\/labestiadeportiva.com\/lbd\/la-punta-pude-cambiar-entre-semana\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">La punta puede cambiar entre semana<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":2051,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,1],"tags":[251,17,48],"_links":{"self":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/2050"}],"collection":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/comments?post=2050"}],"version-history":[{"count":6,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/2050\/revisions"}],"predecessor-version":[{"id":2077,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/2050\/revisions\/2077"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media\/2051"}],"wp:attachment":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media?parent=2050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/categories?post=2050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/tags?post=2050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}