{"id":21232,"date":"2016-08-17T10:08:12","date_gmt":"2016-08-17T13:08:12","guid":{"rendered":"http:\/\/labestiadeportiva.com\/lbd\/?p=21232"},"modified":"2016-08-17T13:53:54","modified_gmt":"2016-08-17T16:53:54","slug":"mensaje-esperanzador-con-oro-incluido","status":"publish","type":"post","link":"https:\/\/labestiadeportiva.com\/lbd\/mensaje-esperanzador-con-oro-incluido\/","title":{"rendered":"Mensaje esperanzador con Oro incluido"},"content":{"rendered":"<p>Por Agust\u00edn \u201cColo\u201d Aguirre (Corresponsal LBD en La Pampa)<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/08\/14713766214976.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-21233\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/08\/14713766214976-300x190.jpg\" alt=\"14713766214976\" width=\"300\" height=\"190\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/08\/14713766214976-300x190.jpg 300w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2016\/08\/14713766214976.jpg 990w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Termin\u00f3 el und\u00e9cimo d\u00eda de estos Juegos Ol\u00edmpicos para la delegaci\u00f3n Argentina. Vaya que fue positivo, porque en la vela, clase Nacra 17, Santiago Lange y Cecilia Carranza obtuvieron la segunda medalla de oro para el pa\u00eds. Mientras que el hockey masculino, se clasific\u00f3 a la final venciendo claramente al bicampe\u00f3n Ol\u00edmpico, Alemania, asegur\u00e1ndose como m\u00ednimo la presea de plata.<!--more--><\/p>\n<p>La vela fue un deporte que siempre entrego alguna medalla para la Argentina. Pero la alegr\u00eda es inmensa para todo el pa\u00eds, obviamente por la dorada conseguida por Santiago Lange y Cecilia Carranza, pero tambi\u00e9n la historia que hay atr\u00e1s.<\/p>\n<p>Lange el a\u00f1o pasado le diagnosticaron c\u00e1ncer, fue operado le extirparon uno de su pulmones, pero a partir de ese momento se puso como meta tratar de llegar a la cita ol\u00edmpica, y vaya que tuvo sus frutos obtuvo su tercera medalla (2 de bronce junto a Carlos Espinola), pero ahora consigui\u00f3 la segunda medalla de oro para la Argentina, tras cosechar 77 puntos y quedar primero en el clasificaci\u00f3n general.<\/p>\n<p>El hockey masculino, \u201cLos Leones\u201d, se jugaban una brava parada, enfrentaba al bicampe\u00f3n ol\u00edmpico Alemania, y jugaron un partido perfecto. Los goles argentos fueron obra de Gonzalo Peilatt en tres oportunidades, Joaqu\u00edn Minini y Lucas Vila mientras que para los alemanes descontaron Furste y Ruhr cerrando el marcador 5 a 2.<\/p>\n<p>La selecci\u00f3n Argentina jugar\u00e1 la final de los Juegos Ol\u00edmpicos por primera vez en la historia. Con esta definici\u00f3n el entrenador nacional \u201cChapa\u201d Retegui consigue su segunda final ol\u00edmpica (la primera fue con \u201cLas Leonas). El juego por el oro ser\u00e1 el d\u00eda jueves a las 17 horas.<\/p>\n<p><span style=\"color: #0000ff;\">Resultados D\u00eda 11 (16\/8)<\/span><br \/>\nEquitaci\u00f3n<br \/>\nSalto individual &#8211; segunda clasificaci\u00f3n : Mat\u00edas Albarrac\u00edn, Jos\u00e9 Mar\u00eda Larocca, Bruno Passaro y Ramiro Quintana 10 horas<br \/>\nSalto por equipos &#8211; Serie 1 &#8211; segunda clasificaci\u00f3n: Mat\u00edas Albarrac\u00edn, Jos\u00e9 Mar\u00eda Larocca, Bruno Passaro y Ramiro Quintana 10 horas<br \/>\nHockey sobre C\u00e9sped Masculino Semifinal Argentina \/ Alemania 5-2 (Gonzalo Peilattx3\/Joaqu\u00edn Menini \/ Lucas Vila)<br \/>\nVela Laser | En la Medal Race, Julio Alsogaray fue descalificado y finaliz\u00f3 10\u00b0 en la clasificaci\u00f3n general.<br \/>\nFinn | En la MedalRace, Facundo Olezza fue 7\u00b0 y termin\u00f3 9\u00b0 en la clasificaci\u00f3n general.<br \/>\nNacra 17 | Santiago Lange y Cecilia Carranza, Medalla de Oro.<br \/>\n49erFX, Yago y Klaus Lange finalizaron 7\u00ba en la general y clasificaron a la medalrace<br \/>\nBoxeo: Categor\u00eda hasta 56 kilos &#8211; Cuartos de final Alberto Meli\u00e1n \/ Murodjon Akhmadaliev (Uzbekist\u00e1n) perdi\u00f3 en KOT en el primer round<\/p>\n<p><span style=\"color: #0000ff;\">Mi\u00e9rcoles 17\/8 D\u00eda 12<\/span><br \/>\nB\u00e1squet Cuartos De Final: Argentina\/Estados Unidos 18:45<br \/>\nAtletismo Lanzamiento de Jabalina: Braian Toledo 20:30<br \/>\nV\u00f3ley Masculino Cuartos De Final: Argentina\/Brasil 22:30<\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 1.034<\/span><span class='epvc-label'> veces le\u00edda<\/span><\/div>\n<div class=\"jwsharethis\">\nShare this: \n<br \/>\n<a href=\"mailto:?subject=Mensaje%20esperanzador%20con%20Oro%20incluido&amp;body=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fmensaje-esperanzador-con-oro-incluido%2F\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/email.png\" alt=\"Share this page via Email\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.stumbleupon.com\/submit?url=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fmensaje-esperanzador-con-oro-incluido%2F&amp;title=Mensaje+esperanzador+con+Oro+incluido\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/su.png\" alt=\"Share this page via Stumble Upon\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/digg.com\/submit?url=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fmensaje-esperanzador-con-oro-incluido%2F&amp;title=Mensaje+esperanzador+con+Oro+incluido\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/digg.png\" alt=\"Share this page via Digg this\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fmensaje-esperanzador-con-oro-incluido%2F&amp;t=Mensaje+esperanzador+con+Oro+incluido\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/fb.png\" alt=\"Share this page via Facebook\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/twitter.com\/intent\/tweet?text=I+like+https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fmensaje-esperanzador-con-oro-incluido%2F&amp;title=Mensaje+esperanzador+con+Oro+incluido\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/twitter.png\" alt=\"Share this page via Twitter\" \/>\n<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por Agust\u00edn \u201cColo\u201d Aguirre (Corresponsal LBD en La Pampa) Termin\u00f3 el und\u00e9cimo d\u00eda de estos Juegos Ol\u00edmpicos para la delegaci\u00f3n Argentina. Vaya que fue positivo, porque en la vela, clase Nacra 17, Santiago Lange y Cecilia Carranza obtuvieron la segunda medalla de oro para el pa\u00eds. Mientras que el hockey masculino, se clasific\u00f3 a la &hellip; <a href=\"https:\/\/labestiadeportiva.com\/lbd\/mensaje-esperanzador-con-oro-incluido\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Mensaje esperanzador con Oro incluido<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":21233,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,2773,1],"tags":[4829,83,2771],"_links":{"self":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/21232"}],"collection":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/comments?post=21232"}],"version-history":[{"count":2,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/21232\/revisions"}],"predecessor-version":[{"id":21243,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/21232\/revisions\/21243"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media\/21233"}],"wp:attachment":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media?parent=21232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/categories?post=21232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/tags?post=21232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}