{"id":25085,"date":"2017-08-01T10:40:20","date_gmt":"2017-08-01T13:40:20","guid":{"rendered":"http:\/\/labestiadeportiva.com\/lbd\/?p=25085"},"modified":"2017-08-01T10:40:20","modified_gmt":"2017-08-01T13:40:20","slug":"balance-sobre-hielo","status":"publish","type":"post","link":"https:\/\/labestiadeportiva.com\/lbd\/balance-sobre-hielo\/","title":{"rendered":"Balance sobre hielo"},"content":{"rendered":"<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20525869_1542484285818101_2916549364592661148_n.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-25095\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20525869_1542484285818101_2916549364592661148_n-300x205.jpg\" alt=\"20525869_1542484285818101_2916549364592661148_n\" width=\"300\" height=\"205\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20525869_1542484285818101_2916549364592661148_n-300x205.jpg 300w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20525869_1542484285818101_2916549364592661148_n.jpg 361w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Finaliz\u00f3 el viernes por la noche la 13\u00ba edici\u00f3n de la \u201cCopa Fin del Mundo\u201d de hockey sobre hielo organizada por el Club Andino Ushuaia. Ocho intensos d\u00edas de competencia en la pista municipal Carlos \u201cTachuela\u201d Oyarz\u00fan. CAU \u201cHijos de la Laguna\u201d domin\u00f3 el segmento mayor, las damas locales triunfaron sobre las porte\u00f1as mientras que ACEMHH se qued\u00f3 con el Sub 14.<!--more--><\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20476427_1542494692483727_8737904281683064526_n.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-25097\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20476427_1542494692483727_8737904281683064526_n-300x165.jpg\" alt=\"20476427_1542494692483727_8737904281683064526_n\" width=\"300\" height=\"165\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20476427_1542494692483727_8737904281683064526_n-300x165.jpg 300w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20476427_1542494692483727_8737904281683064526_n.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Las \u00faltimas dos semanas de julio nuestra ciudad fue el escenario de la tradicional competencia de hockey sobre hielo, \u201cCopa Fin del Mundo\u201d, disputando en esta oportunidad su 13\u00ba edici\u00f3n, organizada por el CAU siendo fiscalizada por la Federaci\u00f3n Argentina de Hockey sobre Hielo FAHH.<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20431304_1542484522484744_2318063381589684126_n.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-25087\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20431304_1542484522484744_2318063381589684126_n-300x159.jpg\" alt=\"20431304_1542484522484744_2318063381589684126_n\" width=\"300\" height=\"159\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20431304_1542484522484744_2318063381589684126_n-300x159.jpg 300w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20431304_1542484522484744_2318063381589684126_n.jpg 794w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Como es de p\u00fablico conocimiento la pista de patinaje se entreg\u00f3 en concesi\u00f3n a la empresa GDS, quienes a trav\u00e9s de mucho esfuerzo lograron abrir la pista para que dicha competencia se desarrolle dentro de los plazos estipulados por la organizaci\u00f3n.<\/p>\n<p>La etapa de infantiles se concret\u00f3 entre el jueves 20 y s\u00e1bado 22 de Julio. Debido a la incertidumbre sobre la apertura de la pista la mayor\u00eda de los clubes invitados desistieron de participar, resultando la competencia de menores con \u00fanicamente una categor\u00eda infantil compuesta de dos equipos Sub 14, CAU y de ACEMHH.<\/p>\n<p>El sistema de juego propuesto fue al mejor de tres partidos. ACEMHH se impuso en los primeros dos encuentros transform\u00e1ndose en el\u00a0 campe\u00f3n de la edici\u00f3n.<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20525744_1542484612484735_4198719562835129068_n.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-25094\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20525744_1542484612484735_4198719562835129068_n-300x165.jpg\" alt=\"20525744_1542484612484735_4198719562835129068_n\" width=\"300\" height=\"165\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20525744_1542484612484735_4198719562835129068_n-300x165.jpg 300w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20525744_1542484612484735_4198719562835129068_n.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>El tercer partido se realiz\u00f3 a modo de incentivo tanto para los visitantes, quienes disfrutan de la experiencia de jugar en una cancha ol\u00edmpica, como para los locales ansiosos de hielo dada la tard\u00eda apertura de la pista.<\/p>\n<p>Queda una gran expectativa para el 2018 y profundas tareas de difusi\u00f3n para generar un encuentro deportivo con m\u00e1s asistencia.<\/p>\n<p>De manera simult\u00e1nea a estos partidos se realizaron actividades recreativas a modo de promoci\u00f3n de la disciplina con los peque\u00f1os Sub 10, Sub 12 y j\u00f3venes Sub 16 del CAU como de Los \u00d1ires, a los que se sumaron algunos ni\u00f1os de Buenos Aires.<\/p>\n<p>Pese a no haber realizado entrenamientos en el hielo, fue posible hacer una pre temporada en el gimnasio del CAU y entrenamientos en roller, sumado a algunos encuentros en la \u201cLaguna del Diablo\u201d, permiti\u00f3 un desempe\u00f1o interesante.<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20431522_1542484549151408_4471159051639375279_n.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-25088\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20431522_1542484549151408_4471159051639375279_n-300x219.jpg\" alt=\"20431522_1542484549151408_4471159051639375279_n\" width=\"300\" height=\"219\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20431522_1542484549151408_4471159051639375279_n-300x219.jpg 300w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20431522_1542484549151408_4471159051639375279_n.jpg 497w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Las categor\u00edas mayores y damas comenzaron la acci\u00f3n desde el domingo 23 al s\u00e1bado28 de Julio. Afortunadamente el clima permiti\u00f3 el desarrollo del fixture como estaba planificado, solo se suspendi\u00f3 un solo partido amistoso de damas debido a lluvia.<\/p>\n<p>En mayores se presentaron 5 equipos, CAU\u201dHijos de la Laguna\u201d, CAU \u201cProhibido Patinar\u201d, Los \u00d1ires, ACEMHH y Ovejas Negras, los \u00faltimos dos de Buenos Aires. El sistema planteado fue una ronda de clasificaci\u00f3n todos contra todos, semifinal y final.<\/p>\n<p>El resultado de fase clasificatoria arroj\u00f3 las siguientes posiciones,\u00a0 1\u00b0 CAU \u201cHDL\u201d, 2\u00b0 Los \u00d1ires, 3\u00b0 ACEMHH, 4\u00b0 CAU \u201cPP\u201d y 5\u00b0 Ovejas Negras. En la etapa de eliminatorias se realizaron los cruces de 1\u00b0 ante 4\u00b0 y 2\u00b0 frente a 3\u00b0. El equipo clasificado 5\u00b0, Ovejas Negras, particip\u00f3 de un partido amistoso enfrentando al CAU versi\u00f3n Sub 16.<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20476227_1542484375818092_4319080133759900737_n.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-25091\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20476227_1542484375818092_4319080133759900737_n-300x202.jpg\" alt=\"20476227_1542484375818092_4319080133759900737_n\" width=\"300\" height=\"202\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20476227_1542484375818092_4319080133759900737_n-300x202.jpg 300w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20476227_1542484375818092_4319080133759900737_n.jpg 449w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>La jornada definitoria, viernes 28 por la noche, se realizaron los dos choques finales. Los equipos que perdieron las semifinales, CAU\u201d PP\u201d \u00a0y Los \u00d1ires, disputaron el 3\u00b0 puesto, obteniendo el podio el equipo de \u00d1ires; posteriormente CAU \u201cHDL\u201d y ACEMHH dirimieron el t\u00edtulo 2017 resultando campe\u00f3n de la \u201cCopa Fin del Mundo\u201d CAU \u201cHijos de la Laguna\u201d quien se impuso por un categ\u00f3rico 5\u00a0 a 1 finalizando la competencia en forma invicta.<\/p>\n<p>En el segmento damas se presentaron dos equipos, CAU y ACEMHH. El sistema de juego fue a mejor de tres partidos. En el primer juego las due\u00f1as de casa comenzaron perdiendo por \u00a02 a 0 pudiendo revertir la historia y dar vuelta el resultado para llevarse una valiosa victoria por 3 a 2.<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20431233_1542484572484739_2773476156097748151_n.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-25086\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20431233_1542484572484739_2773476156097748151_n-300x165.jpg\" alt=\"20431233_1542484572484739_2773476156097748151_n\" width=\"300\" height=\"165\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20431233_1542484572484739_2773476156097748151_n-300x165.jpg 300w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20431233_1542484572484739_2773476156097748151_n.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>El segundo partido finaliz\u00f3 igualado en dos tantos, en el Over Time (Tiempo Extra) Ana Tibaud\u00edn le dio el triunfo y el t\u00edtulo a las \u201cchicas\u201d ushuaienses. Para destacar la preparaci\u00f3n f\u00edsica de las jugadoras del CAU quienes desde febrero entrenan en\u00a0 gimnasio marcando la deferencia en el cierre de los partidos.<\/p>\n<p>El balance general del evento fue sumamente positivo. Considerando las adversidades previas, que inclusive hicieron pensar a la organizaci\u00f3n en suspender la competencia.<\/p>\n<p>Haber contado con la participaci\u00f3n de cuatro clubes, tres categor\u00edas y nueve equipos que reunieron alrededor de 100 jugadores deja en evidencia que el hockey sobre hielo se encuentra en pleno crecimiento.<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20431339_1542494659150397_555338375853514156_n.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-25096\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20431339_1542494659150397_555338375853514156_n-300x165.jpg\" alt=\"20431339_1542494659150397_555338375853514156_n\" width=\"300\" height=\"165\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20431339_1542494659150397_555338375853514156_n-300x165.jpg 300w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20431339_1542494659150397_555338375853514156_n.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Desde la organizaci\u00f3n destacaron el apoyo de entidades y comercios quienes apoyaron de diferentes formas haciendo posible la concreci\u00f3n exitosa del evento, ellos fueron: GDS, NewSan, Popper, In.Fue.Tur., Municipalidad de Ushuaia, CAEF, Tante Sara, Innovar y Aerol\u00edneas Argentinas.<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20476220_1542484645818065_2243007390241908289_n.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-25090\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20476220_1542484645818065_2243007390241908289_n-300x165.jpg\" alt=\"20476220_1542484645818065_2243007390241908289_n\" width=\"300\" height=\"165\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20476220_1542484645818065_2243007390241908289_n-300x165.jpg 300w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2017\/08\/20476220_1542484645818065_2243007390241908289_n.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 1.249<\/span><span class='epvc-label'> veces le\u00edda<\/span><\/div>\n<div class=\"jwsharethis\">\nShare this: \n<br \/>\n<a href=\"mailto:?subject=Balance%20sobre%20hielo&amp;body=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fbalance-sobre-hielo%2F\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/email.png\" alt=\"Share this page via Email\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.stumbleupon.com\/submit?url=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fbalance-sobre-hielo%2F&amp;title=Balance+sobre+hielo\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/su.png\" alt=\"Share this page via Stumble Upon\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/digg.com\/submit?url=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fbalance-sobre-hielo%2F&amp;title=Balance+sobre+hielo\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/digg.png\" alt=\"Share this page via Digg this\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fbalance-sobre-hielo%2F&amp;t=Balance+sobre+hielo\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/fb.png\" alt=\"Share this page via Facebook\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/twitter.com\/intent\/tweet?text=I+like+https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Fbalance-sobre-hielo%2F&amp;title=Balance+sobre+hielo\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/twitter.png\" alt=\"Share this page via Twitter\" \/>\n<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Finaliz\u00f3 el viernes por la noche la 13\u00ba edici\u00f3n de la \u201cCopa Fin del Mundo\u201d de hockey sobre hielo organizada por el Club Andino Ushuaia. Ocho intensos d\u00edas de competencia en la pista municipal Carlos \u201cTachuela\u201d Oyarz\u00fan. CAU \u201cHijos de la Laguna\u201d domin\u00f3 el segmento mayor, las damas locales triunfaron sobre las porte\u00f1as mientras que &hellip; <a href=\"https:\/\/labestiadeportiva.com\/lbd\/balance-sobre-hielo\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Balance sobre hielo<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":25095,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,6,2233,1],"tags":[760,3237,42,139,83],"_links":{"self":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/25085"}],"collection":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/comments?post=25085"}],"version-history":[{"count":1,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/25085\/revisions"}],"predecessor-version":[{"id":25098,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/25085\/revisions\/25098"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media\/25095"}],"wp:attachment":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media?parent=25085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/categories?post=25085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/tags?post=25085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}