{"id":26980,"date":"2018-01-26T15:16:12","date_gmt":"2018-01-26T18:16:12","guid":{"rendered":"http:\/\/labestiadeportiva.com\/lbd\/?p=26980"},"modified":"2018-01-26T15:23:22","modified_gmt":"2018-01-26T18:23:22","slug":"todos-a-las-17","status":"publish","type":"post","link":"https:\/\/labestiadeportiva.com\/lbd\/todos-a-las-17\/","title":{"rendered":"Todos a las 17"},"content":{"rendered":"<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/01\/27073126_1717535838312944_1660166591446374391_n.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-26981\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/01\/27073126_1717535838312944_1660166591446374391_n-300x136.jpg\" alt=\"27073126_1717535838312944_1660166591446374391_n\" width=\"300\" height=\"136\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/01\/27073126_1717535838312944_1660166591446374391_n-300x136.jpg 300w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2018\/01\/27073126_1717535838312944_1660166591446374391_n.jpg 660w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Se confirmaron horarios y ternas arbitrales para la 1\u00ba fecha del Torneo Federal \u201cC\u201d dentro de la Zona 1 Regi\u00f3n Patag\u00f3nica Sur. Walter Barrera controlar\u00e1 el partido en Ushuaia mientras que Jos\u00e9 Pe\u00f1arrieta har\u00e1 lo propio en R\u00edo Grande. Por tercer a\u00f1o consecutivo el arbitraje fueguino estar\u00e1 representado \u00fanicamente por ushuaienses.<!--more--><\/p>\n<p>Los sint\u00e9ticos municipales, del Barrio AGP, en el norte de la isla y \u201cHugo Lumbreras\u201d de la capital provincial ser\u00e1n los escenarios para el comienzo de la competencia nacional el pr\u00f3ximo domingo por la tarde.<\/p>\n<p>Pablo Ru\u00edz y Leandro Carracedo Bosch ser\u00e1n los l\u00edneas en Ushuaia mientras que Germ\u00e1n Acevedo junto a Nicol\u00e1s Zapata colaborar\u00e1n con Pe\u00f1arrieta en R\u00edo Grande.<\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 1.210<\/span><span class='epvc-label'> veces le\u00edda<\/span><\/div>\n<div class=\"jwsharethis\">\nShare this: \n<br \/>\n<a href=\"mailto:?subject=Todos%20a%20las%2017&amp;body=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Ftodos-a-las-17%2F\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/email.png\" alt=\"Share this page via Email\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.stumbleupon.com\/submit?url=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Ftodos-a-las-17%2F&amp;title=Todos+a+las+17\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/su.png\" alt=\"Share this page via Stumble Upon\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/digg.com\/submit?url=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Ftodos-a-las-17%2F&amp;title=Todos+a+las+17\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/digg.png\" alt=\"Share this page via Digg this\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Ftodos-a-las-17%2F&amp;t=Todos+a+las+17\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/fb.png\" alt=\"Share this page via Facebook\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/twitter.com\/intent\/tweet?text=I+like+https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Ftodos-a-las-17%2F&amp;title=Todos+a+las+17\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/twitter.png\" alt=\"Share this page via Twitter\" \/>\n<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Se confirmaron horarios y ternas arbitrales para la 1\u00ba fecha del Torneo Federal \u201cC\u201d dentro de la Zona 1 Regi\u00f3n Patag\u00f3nica Sur. Walter Barrera controlar\u00e1 el partido en Ushuaia mientras que Jos\u00e9 Pe\u00f1arrieta har\u00e1 lo propio en R\u00edo Grande. Por tercer a\u00f1o consecutivo el arbitraje fueguino estar\u00e1 representado \u00fanicamente por ushuaienses. 1.210 veces le\u00edda Share &hellip; <a href=\"https:\/\/labestiadeportiva.com\/lbd\/todos-a-las-17\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Todos a las 17<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":26981,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,6,2491,1],"tags":[2468,3460,17,83,2931],"_links":{"self":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/26980"}],"collection":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/comments?post=26980"}],"version-history":[{"count":2,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/26980\/revisions"}],"predecessor-version":[{"id":26983,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/26980\/revisions\/26983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media\/26981"}],"wp:attachment":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media?parent=26980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/categories?post=26980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/tags?post=26980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}