{"id":3270,"date":"2013-03-05T14:26:51","date_gmt":"2013-03-05T14:26:51","guid":{"rendered":"http:\/\/labestiadeportiva.com\/lbd\/?p=3270"},"modified":"2013-03-05T14:26:51","modified_gmt":"2013-03-05T14:26:51","slug":"acuna-y-aravena-los-duenos-del-bosque","status":"publish","type":"post","link":"https:\/\/labestiadeportiva.com\/lbd\/acuna-y-aravena-los-duenos-del-bosque\/","title":{"rendered":"Acu\u00f1a y Aravena los \u201cdue\u00f1os\u201d del bosque"},"content":{"rendered":"<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1564.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-3271\" title=\"_MG_1564\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1564-300x210.jpg\" alt=\"\" width=\"300\" height=\"210\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1564-300x210.jpg 300w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1564.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1567.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-3272\" title=\"_MG_1567\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1567-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1567-300x225.jpg 300w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1567.jpg 638w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Se realiz\u00f3 el pasado s\u00e1bado la primera edici\u00f3n del \u201cDesaf\u00edo Ushuaia\u201d. El equipo denominado \u201cNunatak\u201d conformado por Walter Acu\u00f1a y Marcos Aravena se qued\u00f3 con el triunfo empleando un tiempo de 6 horas 18 minutos y 50 segundos. 29 parejas presentes. Se realizaron 43 kil\u00f3metros con bicicletas de monta\u00f1a y 17 de pedestrismo. La prueba se inici\u00f3 en Haruwen finalizando en Tierra Mayor.<!--morePara leer Click Aqu\u00ed--><\/p>\n<p>El debut absoluto de la competencia se desarroll\u00f3 durante las primeras horas del s\u00e1bado, los participantes se concentraron a partir de las 6 en el sector del Centro Invernal Haruwen, para desde las 7 comenzar el trayecto en bicicletas de monta\u00f1a.<\/p>\n<p>El tramo inicial se realiz\u00f3 hasta las cercan\u00edas del r\u00edo Palacios donde efectuaron el cruce del Paso Garibaldi por el camino viejo, para cerca de la costa del Lago Escondido encontrarse con el primer puesto de neutralizaci\u00f3n donde los equipos tuvieron que superar la primera prueba de ingenio.<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1539.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-3273\" title=\"_MG_1539\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1539-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1539-300x200.jpg 300w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1539.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Nuevo paso por la ruta N\u00b0 3 hasta llegar al cruce de la ruta 119 la cual tomaron hasta su finalizaci\u00f3n sector de transici\u00f3n entre el ciclismo y el pedestrismo, tiempo de hidrataci\u00f3n donde los organizadores pusieron a disposici\u00f3n de los deportistas frutas, bebidas y control m\u00e9dico de ser necesario.<\/p>\n<p>El inicio de la segunda parte de la prueba fue con nueva neutralizaci\u00f3n incluida asimismo los equipos fueron exigidos al m\u00e1ximo pues este tramo presentaba una mayor dificultad por lo complicado del terreno que invitaba a perderse, la fina orientaci\u00f3n de los corredores fue crucial para poder llegar al final de la competencia.<\/p>\n<p>Los equipos recorrieron el sector que une el valle del R\u00edo Palacios con el del Alvear por el conocido \u201cPaso Franc\u00e9s\u201d finalizando en las puestas del Centro Invernal Tierra Mayor donde finalmente completaron los 61 k de la exigente prueba.<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1546.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-3274\" title=\"_MG_1546\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1546-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1546-300x200.jpg 300w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1546.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>En la zona del arco de llegada se congreg\u00f3 una importante cantidad de p\u00fablico, prensa, organizadores, familiares y amigos de los osados participantes quienes a medida que completaban el recorrido fueron recibidos con aplausos.<\/p>\n<p>El domingo por la tarde, en instalaciones del shopping \u201cPaseo del Fuego\u201d, se realiz\u00f3 la entrega de premios y distinciones de la novedosa competencia.<br \/>\nSaldo altamente positivo en todo sentido, buena organizaci\u00f3n, interesante n\u00famero de participantes, auspiciantes apoyando el evento lo que hace presagiar que el \u201cDesaf\u00edo Ushuaia\u201d se quedar\u00e1 entre nosotros por mucho tiempo.<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1568.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-3276\" title=\"_MG_1568\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1568-300x182.jpg\" alt=\"\" width=\"300\" height=\"182\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1568-300x182.jpg 300w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1568.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><span style=\"color: #0000ff;\">Los Equipos<\/span><br \/>\nBianchi Mart\u00edn\/Caballero Jos\u00e9 Augusto \u201cLOS PROFES\u201d<br \/>\nCayo Walter\/Zuloaga Mat\u00edas \u201cLOS FILOSOS\u201d<br \/>\nLuj\u00e1n N\u00e9stor\/Cuevas Jes\u00fas \u201cLOS GRINGOS\u201d<br \/>\nSan Mart\u00edn Mar\u00eda E.\/Bertoletti Fernando \u201cOUCH\u00c1\u201d<br \/>\nVillalta Sebasti\u00e1n\/Gustavo Gir\u00f3 \u201cANTARTUR\u201d<br \/>\nRavazi Claudio\/Ortube Dami\u00e1n \u201cLOS CIRUJAS\u201d<br \/>\nHerrainz Leandro\/Gonz\u00e1lez Gavil\u00e1n Mart\u00edn \u201cINFUE TEAM<br \/>\nCapanna Lisandro\/Hondarre Diego \u201cCHALT\u00c9N RECARGADO\u201d<br \/>\nMart\u00ednez Carlos\/Rayez Sebasti\u00e1n \u201cPING\u00dcINO TEAM\u201d<br \/>\nBertotto Tom\u00e1s\/Bar\u00e9 Gustavo \u201cPASEO DEL FUEGO\u201d<br \/>\nPalacios Marcelo\/Naguila N\u00e9stor \u201cLOS PELADOS\u201d<br \/>\nSan Pietro Pablo\/Caldelari Jorge \u201cDRINK TEAM\u201d<br \/>\nUboldi Guillermo\/Potti Juan Francisco \u201cKAMALI\u201d<br \/>\nRivarola Leopoldo\/Cataneo Ariel \u201cTEAM CASA LINDA\u201d<br \/>\nAravena Marcos\/Acu\u00f1a Walter \u201cNUNATAK\u201d<br \/>\nSommariva Gustavo\/Ledesma Gustavo \u201cLOS CASTORES\u201d<br \/>\nCARDENAS Jorge\/Aravena Norman \u201cLOS YAMANAS\u201d<br \/>\nL\u00f3pez Carlos\/Via\u00f1a Constanza \u201cSOUTHERN FORCE\u201d<br \/>\nG\u00f3mez Andr\u00e9s\/Moriconi Marco \u201cLOS ESCURSIONISTAS\u201d<br \/>\nFerman Germ\u00e1n\/Beriau Julio \u201c13 HORAS\u201d<br \/>\nMolinari Walter\/Forastiere Jorge \u201cIN PRESIONANTE\u201d<br \/>\nIrazoque Pablo\/Torres Franco \u201cPAPANATAS TEAM\u201d<br \/>\nStabile Edgar\/Canchi Juan \u201cESCUADRON 44\u201d<br \/>\nMenci Sebasti\u00e1n\/Barrera Pablo \u201cCORRE FOREST\u201d<br \/>\nOrt\u00edz Dar\u00edo\/ Alonso Julio \u201cLOS \u00d1IRES TEAM\u201d<br \/>\nCastro Gabriel\/Castro Mat\u00edas \u201cB RAN Q LAS TIMA\u201d<br \/>\nRegis Guignier\/ Lotc Benair \u201cGONES RAIDEURS\u201d<br \/>\nAvalos Francisco\/Barrios Vera Santiago \u201cDOS PARA TRIUNFAR\u201d<br \/>\nBurgos Joaqu\u00edn\/C\u00e1ceres Miguel \u201cJ.M.\u201d<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1575.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-3277\" title=\"_MG_1575\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1575-300x216.jpg\" alt=\"\" width=\"300\" height=\"216\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1575-300x216.jpg 300w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1575.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><span style=\"color: #0000ff;\">Posiciones Finales por Categor\u00eda<\/span><br \/>\nCaballeros \u201cA\u201d<br \/>\nEquipo\u00a0 Tiempo<br \/>\n<span style=\"color: #ff0000;\">1\u00b0 Nunatak 6:18:50<\/span><br \/>\n2\u00b0 Antartur 6:27:07<br \/>\n3\u00b0 Forest 6:55:58<br \/>\n4\u00b0 Gones Raideurs 7:06:40<br \/>\n5\u00b0 JM 7:24:55<br \/>\n6\u00b0 Los Excursionistas 7:39:31<br \/>\n7\u00b0 Los profes 7:54:59<br \/>\n8\u00b0 Casa Linda 7:56:16<br \/>\n9\u00b0 Los \u00f1ires Team 7:59;52<br \/>\n10\u00b0 Infue Team 7:59:52<br \/>\n12\u00b0 Tarde pero Seguro 8:44:25<br \/>\n13\u00b0 Los Filosos 8:51:28<br \/>\n14\u00b0 B ran Q Las Tima 9:06:22<br \/>\n15\u00b0 Chalten Recargado 9:17:28<br \/>\n16\u00b0 Los Cirujas\u00a0 11:02:34<br \/>\n17\u00b0 Los Gringos 11:02:34<br \/>\n18\u00b0 Kalami 11:17:30<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1561.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-3278\" title=\"_MG_1561\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1561-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1561-300x200.jpg 300w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1561.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Caballeros \u201cB\u201d<br \/>\n<span style=\"color: #0000ff;\">1\u00b0 Cien a\u00f1os no son nada 7:20:18<\/span><br \/>\n2\u00b0 Ping\u00fcinos Team\u00a0 8:12:06<br \/>\n3\u00b0 Los castores Team 8:19<br \/>\n4\u00b0 Los Y\u00e1manas 8:21:04<br \/>\n5\u00b0\u00a0 13 Horas 9:31:42<br \/>\n6\u00b0 Los Pelados 9:57:44<br \/>\n7\u00b0 Escuadr\u00f3n 44\u00a0 10:15:35<br \/>\n8\u00b0 Drink Team\u00a0 10:15:35<br \/>\n9\u00b0 Paseo del Fuego<br \/>\n11\u00b0 In presionante\u00a0 11:10:20<\/p>\n<p>Mixto<br \/>\n1\u00b0 Oucha 8:53:44<br \/>\n2\u00b0 Souther Force 11:14:50<\/p>\n<p><a href=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1576.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-3279\" title=\"_MG_1576\" src=\"http:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1576-300x163.jpg\" alt=\"\" width=\"300\" height=\"163\" srcset=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1576-300x163.jpg 300w, https:\/\/labestiadeportiva.com\/lbd\/wp-content\/uploads\/2013\/03\/MG_1576.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<div class='epvc-post-count'><span class='epvc-eye'><\/span>  <span class=\"epvc-count\"> 1.289<\/span><span class='epvc-label'> veces le\u00edda<\/span><\/div>\n<div class=\"jwsharethis\">\nShare this: \n<br \/>\n<a href=\"mailto:?subject=Acu%C3%B1a%20y%20Aravena%20los%20%E2%80%9Cdue%C3%B1os%E2%80%9D%20del%20bosque&amp;body=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Facuna-y-aravena-los-duenos-del-bosque%2F\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/email.png\" alt=\"Share this page via Email\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.stumbleupon.com\/submit?url=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Facuna-y-aravena-los-duenos-del-bosque%2F&amp;title=Acu%C3%B1a+y+Aravena+los+%E2%80%9Cdue%C3%B1os%E2%80%9D+del+bosque\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/su.png\" alt=\"Share this page via Stumble Upon\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/digg.com\/submit?url=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Facuna-y-aravena-los-duenos-del-bosque%2F&amp;title=Acu%C3%B1a+y+Aravena+los+%E2%80%9Cdue%C3%B1os%E2%80%9D+del+bosque\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/digg.png\" alt=\"Share this page via Digg this\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Facuna-y-aravena-los-duenos-del-bosque%2F&amp;t=Acu%C3%B1a+y+Aravena+los+%E2%80%9Cdue%C3%B1os%E2%80%9D+del+bosque\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/fb.png\" alt=\"Share this page via Facebook\" \/>\n<\/a>\n<a target=\"_blank\" href=\"http:\/\/twitter.com\/intent\/tweet?text=I+like+https%3A%2F%2Flabestiadeportiva.com%2Flbd%2Facuna-y-aravena-los-duenos-del-bosque%2F&amp;title=Acu%C3%B1a+y+Aravena+los+%E2%80%9Cdue%C3%B1os%E2%80%9D+del+bosque\">\n<img src=\"https:\/\/labestiadeportiva.com\/lbd\/wp-content\/plugins\/jw-share-this\/twitter.png\" alt=\"Share this page via Twitter\" \/>\n<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Se realiz\u00f3 el pasado s\u00e1bado la primera edici\u00f3n del \u201cDesaf\u00edo Ushuaia\u201d. El equipo denominado \u201cNunatak\u201d conformado por Walter Acu\u00f1a y Marcos Aravena se qued\u00f3 con el triunfo empleando un tiempo de 6 horas 18 minutos y 50 segundos. 29 parejas presentes. Se realizaron 43 kil\u00f3metros con bicicletas de monta\u00f1a y 17 de pedestrismo. La prueba &hellip; <a href=\"https:\/\/labestiadeportiva.com\/lbd\/acuna-y-aravena-los-duenos-del-bosque\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">Acu\u00f1a y Aravena los \u201cdue\u00f1os\u201d del bosque<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":3271,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,4,6,1],"tags":[490,491],"_links":{"self":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/3270"}],"collection":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/comments?post=3270"}],"version-history":[{"count":1,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/3270\/revisions"}],"predecessor-version":[{"id":3280,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/posts\/3270\/revisions\/3280"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media\/3271"}],"wp:attachment":[{"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/media?parent=3270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/categories?post=3270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/labestiadeportiva.com\/lbd\/wp-json\/wp\/v2\/tags?post=3270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}